{"id":69191,"date":"2025-11-28T12:34:55","date_gmt":"2025-11-28T12:34:55","guid":{"rendered":"https:\/\/cortho.org\/service\/coalicion-tarsal\/"},"modified":"2026-01-02T05:03:06","modified_gmt":"2026-01-02T05:03:06","slug":"coalicion-tarsal","status":"publish","type":"service","link":"https:\/\/www.cortho.org\/es\/servicio\/coalicion-tarsal\/","title":{"rendered":"Coalici\u00f3n Tarsal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La coalici\u00f3n tarsiana es una afecci\u00f3n en la que dos o m\u00e1s huesos en la parte posterior del pie (los huesos tarsianos) est\u00e1n conectados de forma anormal. Esta conexi\u00f3n puede estar formada por hueso, cart\u00edlago o tejido fibroso. Mientras que algunas personas nunca experimentan s\u00edntomas, otras pueden desarrollar dolor, rigidez o deformidad en el pie plano a medida que crecen y los huesos del pie maduran. El reconocimiento y tratamiento tempranos pueden ayudar a prevenir problemas a largo plazo y restaurar la normalidad de la movilidad.   <\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 frecuencia tiene y qui\u00e9n la padece? (Epidemiolog\u00eda) <\/h3>\n\n<p class=\"wp-block-paragraph\">La coalici\u00f3n tarsiana se encuentra en aproximadamente el 1\u20132% de la poblaci\u00f3n. La mayor\u00eda de los casos son cong\u00e9nitos, es decir, la condici\u00f3n est\u00e1 presente desde el nacimiento, aunque los s\u00edntomas suelen aparecer entre los 8 y los 16 a\u00f1os a medida que los huesos maduran. <\/p>\n\n<ul class=\"wp-block-list\">\n<li>La <strong>coalici\u00f3n calcaneosnavicular<\/strong> (entre el tal\u00f3n y los huesos naviculares) suele aparecer entre los 8 y los 12 a\u00f1os.<\/li>\n\n\n\n<li><strong>La coalici\u00f3n talocalcaneal<\/strong> (entre el taludo y el hueso del tal\u00f3n) suele presentarse entre los 12 y los 15 a\u00f1os.<br\/>Afecta tanto a hombres como a mujeres por igual, y ambos pies est\u00e1n implicados en aproximadamente la mitad de los casos.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">Por qu\u00e9 ocurre &#8211; Causas (Etiolog\u00eda y Fisiopatolog\u00eda)<\/h3>\n\n<p class=\"wp-block-paragraph\">La mayor\u00eda de las coaliciones tarsianales son cong\u00e9nitas y son causadas por un error de desarrollo durante el crecimiento fetal, cuando los huesos tarsales no se separan correctamente. Esto resulta del fallo de la segmentaci\u00f3n mesenquimatosa en el embri\u00f3n. Con el tiempo, el puente fibroso o cartilaginoso puede consolidarse hasta convertirse en hueso.  <\/p>\n\n<p class=\"wp-block-paragraph\">Las causas adquiridas menos comunes incluyen:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Trauma<\/li>\n\n\n\n<li>Infecci\u00f3n<\/li>\n\n\n\n<li>Artritis degenerativa<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Los factores gen\u00e9ticos tambi\u00e9n pueden influir, con algunos casos vinculados a mutaciones en el gen FGFR3.<\/p>\n\n<p class=\"wp-block-paragraph\">La conexi\u00f3n anormal limita el movimiento entre los huesos tarsianos\u2014especialmente en la articulaci\u00f3n subtalar\u2014y cambia la forma en que se mueve el pie. Este movimiento restringido provoca estr\u00e9s mec\u00e1nico, lo que provoca flatfoot, tal\u00f3n valgo (inclinaci\u00f3n del tal\u00f3n hacia dentro) y espasmos musculares dolorosos en la pierna. <\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfC\u00f3mo funciona normalmente una parte del cuerpo? (Anatom\u00eda relevante) <\/h3>\n\n<p class=\"wp-block-paragraph\">Los huesos tarsos \u2014incluyendo el calc\u00e1neo (tal\u00f3n), el tal\u00f3n, los naviculares, cuboides y cuneiformes\u2014 forman la parte posterior y la parte media del pie. Proporcionan flexibilidad, absorben los impactos y permiten caminar y correr con suavidad. Cuando se forma una coalici\u00f3n, estos huesos pierden su capacidad de moverse de forma independiente, lo que limita la flexibilidad y puede alterar la mec\u00e1nica normal de la marcha. Las dos articulaciones m\u00e1s afectadas son:   <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Articulaci\u00f3n talocalcaneal<\/strong> (entre el talus y el calcaneo)<\/li>\n\n\n\n<li><strong>Articulaci\u00f3n calcanonavicular<\/strong> (entre el calc\u00e1neo y el navicular)<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">Lo que puedes sentir &#8211; S\u00edntomas (presentaci\u00f3n cl\u00ednica)<\/h3>\n\n<p class=\"wp-block-paragraph\">Los s\u00edntomas suelen desarrollarse de forma gradual y pueden incluir:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Dolor en el pie o el tobillo, especialmente al caminar o estar de pie<\/li>\n\n\n\n<li>Piernas cansadas o fatigadas<\/li>\n\n\n\n<li>Espasmos musculares que hacen que el pie se gire hacia fuera (pie plano esp\u00e1stico peroneo)<\/li>\n\n\n\n<li>Deformidad en el pie plano en uno o ambos pies<\/li>\n\n\n\n<li>Rigidez y disminuci\u00f3n del movimiento en el tobillo o la parte trasera del pie<\/li>\n\n\n\n<li>Esguinces recurrentes de tobillo debido a la flexibilidad limitada<br\/>Algunas personas permanecen sin s\u00edntomas y son diagnosticadas incidentalmente en im\u00e1genes.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">\u00bfC\u00f3mo encuentran el problema los m\u00e9dicos? (Diagn\u00f3stico e imagen) <\/h3>\n\n<p class=\"wp-block-paragraph\">El diagn\u00f3stico comienza con una evaluaci\u00f3n cl\u00ednica y estudios de imagen.<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Examen f\u00edsico:<\/strong> El m\u00e9dico eval\u00faa el rango de movimiento, la altura del arco y la alineaci\u00f3n de la parte trasera del pie. El arco no reaparece cuando se est\u00e1 de puntillas si hay coalici\u00f3n. <\/li>\n\n\n\n<li><strong>Radiograf\u00edas:<\/strong> La prueba de primera l\u00ednea.\n<ul class=\"wp-block-list\">\n<li>La <em>coalici\u00f3n calcanonenavicular<\/em> muestra el signo de &#8220;nariz de hormiguero&#8221; en la radiograf\u00eda oblicua.<\/li>\n\n\n\n<li><em>La coalici\u00f3n talocalcaneal<\/em> puede mostrar un &#8220;signo C&#8221; en la radiograf\u00eda lateral.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>TAC:<\/strong> Lo ideal para identificar el tipo, tama\u00f1o y ubicaci\u00f3n exacta de una coalici\u00f3n y descartar m\u00faltiples coaliciones.<\/li>\n\n\n\n<li><strong>Resonancia magn\u00e9tica:<\/strong> \u00datil para detectar coaliciones fibrosas o cartilaginosas que no se ven en radiograf\u00edas y para evaluar inflamaci\u00f3n de tejidos blandos.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">Clasificaci\u00f3n<\/h3>\n\n<p class=\"wp-block-paragraph\">Las coaliciones tarsales se clasifican por ubicaci\u00f3n y tipo de tejido:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Por ubicaci\u00f3n:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Calcaneonavicular (m\u00e1s com\u00fan)<\/li>\n\n\n\n<li>Talocalcaneal (segundo m\u00e1s com\u00fan)<\/li>\n\n\n\n<li>Menos comunes: talonavicular, calcaneocuboide, naviculocuneiforme<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Por tipo de tejido:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Fibroso (sindesmosis)<\/li>\n\n\n\n<li>Cartilaginoso (sincrodrosis)<\/li>\n\n\n\n<li>\u00d3seo (sinostosis)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">Otros problemas que pueden parecer similares (diagn\u00f3stico diferencial)<\/h3>\n\n<p class=\"wp-block-paragraph\">Las condiciones que pueden imitar la coalici\u00f3n tarsal incluyen:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Pie plano flexible<\/li>\n\n\n\n<li>Disfunci\u00f3n del tend\u00f3n tibial posterior<\/li>\n\n\n\n<li>S\u00edndrome de los senos paranasales tarsi<\/li>\n\n\n\n<li>Artritis subastragalina<\/li>\n\n\n\n<li>Pie plano esp\u00e1stico peroneal por otras causas<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">Opciones de tratamiento<\/h3>\n\n<p class=\"wp-block-paragraph\"><strong>Atenci\u00f3n no quir\u00fargica<\/strong><br\/>El tratamiento conservador es el primer paso para la mayor\u00eda de los pacientes sintom\u00e1ticos.<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>AINEs:<\/strong> Reduce el dolor y la inflamaci\u00f3n.<\/li>\n\n\n\n<li><strong>Fisioterapia:<\/strong> Incluye estiramientos, masajes, ecograf\u00eda y ejercicios de rango de movimiento.<\/li>\n\n\n\n<li><strong>Ortesis:<\/strong> Las plantillas o soportes personalizados para zapatos alivian la presi\u00f3n y mejoran la alineaci\u00f3n.<\/li>\n\n\n\n<li><strong>Lanzamiento o inmovilizaci\u00f3n:<\/strong> La inmovilizaci\u00f3n a corto plazo en un yeso o bota puede hacer que el pie descanse y reducir los s\u00edntomas.<\/li>\n\n\n\n<li><strong>Inyecciones de esteroides:<\/strong> Reduce la inflamaci\u00f3n y el dolor en la articulaci\u00f3n afectada.<\/li>\n\n\n\n<li><strong>Modificaci\u00f3n de la actividad:<\/strong> Evitar deportes de alto impacto o terrenos irregulares puede ayudar a controlar los s\u00edntomas.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><strong>Atenci\u00f3n quir\u00fargica<\/strong><br\/>Se considera la cirug\u00eda si los s\u00edntomas persisten tras un tratamiento conservador.<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Resecci\u00f3n de Coalici\u00f3n:<\/strong> Se elimina el puente anormal y se coloca tejido blando (grasa, m\u00fasculo o tend\u00f3n) entre los huesos para evitar la recurrencia.\n<ul class=\"wp-block-list\">\n<li><em>Coaliciones calcaneonaviculares:<\/em> A menudo est\u00e1 lleno de m\u00fasculo extensor del dedo corto.<\/li>\n\n\n\n<li><em>Coaliciones talocalcaneales:<\/em> Puede usar una parte del tend\u00f3n largo del flexor del hallucis.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Procedimientos de osteotom\u00eda o realineamiento:<\/strong> Se realiza si existe una deformidad significativa, como la alineaci\u00f3n del valgo.<\/li>\n\n\n\n<li><strong>Arthrodesis (Fusion):<\/strong>\u00a0Used for large coalitions (>50% of the joint surface) or advanced arthritis.\n<ul class=\"wp-block-list\">\n<li>Se puede realizar <em>artrodesis subtalar<\/em> o <em>artrodesis triple<\/em> (fusi\u00f3n de articulaciones subtalar, calco-cuboides y talonaviculares) en casos graves.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">Recuperaci\u00f3n y qu\u00e9 esperar despu\u00e9s del tratamiento<\/h3>\n\n<p class=\"wp-block-paragraph\">Tras la cirug\u00eda, los pacientes suelen llevar yeso o bota durante 3\u20136 semanas, permaneciendo inicialmente sin apoyar peso. A continuaci\u00f3n se realiza fisioterapia gradual para restaurar el movimiento y la fuerza. La mayor\u00eda de los pacientes vuelven a la actividad normal en un plazo de 3\u20136 meses. Los pacientes m\u00e1s j\u00f3venes suelen recuperarse m\u00e1s plenamente y recuperar mejor movimiento que los adultos con coaliciones de larga duraci\u00f3n.   <\/p>\n\n<h3 class=\"wp-block-heading\">Posibles riesgos o efectos secundarios (complicaciones)<\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Resecci\u00f3n incompleta o recurrencia de la coalici\u00f3n<\/li>\n\n\n\n<li>Dolor o rigidez persistentes<\/li>\n\n\n\n<li>Infecci\u00f3n o problemas de heridas<\/li>\n\n\n\n<li>Artritis degenerativa si la coalici\u00f3n implica una zona articular grande<\/li>\n\n\n\n<li>Desalineaci\u00f3n o deformidad residual del pie plano<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">Perspectivas a largo plazo (pron\u00f3stico)<\/h3>\n\n<p class=\"wp-block-paragraph\">El pron\u00f3stico es excelente para pacientes que se someten a una resecci\u00f3n en coalici\u00f3n antes de que se produzcan cambios degenerativos significativos. Alrededor del 80\u201385% experimenta alivio del dolor a largo plazo y recuperaci\u00f3n del movimiento. Los pacientes con coaliciones grandes o artr\u00edticas pueden requerir fusi\u00f3n articular, pero a\u00fan as\u00ed lograr un alivio fiable del dolor y una mejor estabilidad.  <\/p>\n\n<h3 class=\"wp-block-heading\">Costes de bolsillo para el tratamiento<\/h3>\n\n<p class=\"wp-block-paragraph\"><strong>Medicare<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">C\u00f3digo CPT 28116 \u2013 Resecci\u00f3n de la Coalici\u00f3n (Calcaneonavicular\/Talocalcaneal): $153.96<\/p>\n\n<p class=\"wp-block-paragraph\">C\u00f3digo CPT 27685 \u2013 Alargamiento del tend\u00f3n de Aquiles (para correcci\u00f3n de valgo): $151.57<\/p>\n\n<p class=\"wp-block-paragraph\">C\u00f3digo CPT 28300 \u2013 Osteotom\u00eda calc\u00e2nea (por correcci\u00f3n de valgo): $153.01<\/p>\n\n<p class=\"wp-block-paragraph\">C\u00f3digo CPT 28725 \u2013 Fusi\u00f3n subtalar (por artritis avanzada o resecci\u00f3n fallida): 182,74 $<\/p>\n\n<p class=\"wp-block-paragraph\">Medicare Parte B suele cubrir el 80% del coste aprobado de estos procedimientos una vez que se ha cumplido tu franquicia anual, dej\u00e1ndote responsable del 20% restante. Los planes de seguro complementario como Medigap, AARP o Blue Cross Blue Shield generalmente cubren ese 20% restante, minimizando o eliminando gastos de bolsillo por procedimientos aprobados por Medicare. Estos planes se coordinan con Medicare para cubrir la carencia de cobertura y reducir los costes totales para los pacientes.  <\/p>\n\n<p class=\"wp-block-paragraph\">Si tienes un seguro secundario como TRICARE, un plan basado en el empleador o la Administraci\u00f3n de Salud de Veteranos, act\u00faa como pagador secundario. Estos planes suelen cubrir cualquier coaseguro restante o franquicia peque\u00f1a, que normalmente oscila entre 100 y 300 d\u00f3lares, dependiendo de tu plan y red de proveedores. <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Indemnizaci\u00f3n por accidente laboral<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Si tu coalici\u00f3n tarsal se ha desarrollado debido a una lesi\u00f3n laboral o condici\u00f3n de sobreuso, la Compensaci\u00f3n de Trabajadores cubrir\u00e1 todos los costes del tratamiento, incluyendo cirug\u00eda, fisioterapia y cuidados postoperatorios. No tendr\u00e1s gastos de tu bolsillo, ya que la aseguradora del empleador paga directamente todos los tratamientos aprobados. <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Seguro sin culpa<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Si tu coalici\u00f3n tarsiana o la afecci\u00f3n relacionada del pie fue causada o agravada por un accidente de tr\u00e1fico, el seguro sin culpa suele cubrir el coste total del tratamiento, incluyendo la resecci\u00f3n de coalici\u00f3n, el alargamiento del tend\u00f3n y la fusi\u00f3n subtalar. El \u00fanico gasto posible de bolsillo puede ser una peque\u00f1a franquicia o copago, dependiendo de tu p\u00f3liza de seguro. <\/p>\n\n<p class=\"wp-block-paragraph\">Ejemplo<\/p>\n\n<p class=\"wp-block-paragraph\">A Emily Carter le diagnosticaron una coalici\u00f3n tarsiana calcaneosnavicular que limitaba su movimiento y causaba dolor cr\u00f3nico. Se someti\u00f3 a una resecci\u00f3n de coalici\u00f3n (CPT 28116) y alargamiento del tend\u00f3n de Aquiles (CPT 27685). El coste estimado de su bolsillo de Medicare para la resecci\u00f3n fue de 153,96 d\u00f3lares. Como Emily ten\u00eda seguro complementario a trav\u00e9s de Blue Cross Blue Shield, el saldo restante estaba completamente cubierto, lo que la dejaba sin gastos de bolsillo para los procedimientos.   <\/p>\n\n<h3 class=\"wp-block-heading\">Preguntas m\u00e1s frecuentes (FAQ)<\/h3>\n\n<p class=\"wp-block-paragraph\"><strong>Q. \u00bfQu\u00e9 es una coalici\u00f3n tarsal?<\/strong><br\/>Un. Una coalici\u00f3n tarsiana es una conexi\u00f3n anormal entre dos o m\u00e1s huesos del pie, normalmente el calcaneo, el talus y los huesos naviculares, que pueden estar formados por hueso, cart\u00edlago o tejido fibroso.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Q. \u00bfQu\u00e9 causa una coalici\u00f3n tarsal?<\/strong><br\/>Un. La mayor\u00eda de los casos de coalici\u00f3n tarsiana son cong\u00e9nitos, es decir, presentes al nacer, debido a la falta de separaci\u00f3n adecuada de los huesos durante el desarrollo fetal.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Q. \u00bfCu\u00e1ndo suelen aparecer los s\u00edntomas de la coalici\u00f3n tarsal?<\/strong><br\/>R. Los s\u00edntomas suelen aparecer durante la adolescencia, cuando los huesos comienzan a endurecerse, causando rigidez y dolor en el pie.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Q. \u00bfCu\u00e1les son los s\u00edntomas comunes de la coalici\u00f3n tarsal?<\/strong><br\/>R. Los s\u00edntomas m\u00e1s comunes incluyen dolor en los pies, rigidez, pies planos, espasmos musculares y dificultad para caminar o practicar deportes.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Q. \u00bfC\u00f3mo se diagnostica la coalici\u00f3n tarsal?<\/strong><br\/>R. El diagn\u00f3stico implica un examen f\u00edsico, revisi\u00f3n de los s\u00edntomas y estudios de imagen como radiograf\u00edas, tomograf\u00edas computarizadas o resonancias magn\u00e9ticas.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Q. \u00bfQu\u00e9 tratamientos no quir\u00fargicos existen para la coalici\u00f3n tarsal?<\/strong><br\/>R. Los tratamientos no quir\u00fargicos incluyen reposo, inmovilizaci\u00f3n, ortesis, fisioterapia y medicamentos antiinflamatorios.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Q. \u00bfCu\u00e1ndo se considera la cirug\u00eda para la coalici\u00f3n tarsal?<\/strong><br\/>R. Se considera la cirug\u00eda cuando los tratamientos no quir\u00fargicos no alivian los s\u00edntomas y el paciente sufre dolor continuo o movilidad limitada.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Q. \u00bfQu\u00e9 opciones quir\u00fargicas existen para la coalici\u00f3n tarsal?<\/strong><br\/>R. Las opciones quir\u00fargicas incluyen la resecci\u00f3n de la coalici\u00f3n o fusi\u00f3n de las articulaciones afectadas, dependiendo de la gravedad y la localizaci\u00f3n.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Q. \u00bfCu\u00e1l es el tiempo de recuperaci\u00f3n tras la cirug\u00eda de coalici\u00f3n tarsal?<\/strong><br\/>R. La recuperaci\u00f3n var\u00eda, pero a menudo incluye un periodo de inmovilizaci\u00f3n seguido de fisioterapia, con un retorno gradual a la actividad durante varios meses.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Q. \u00bfPuede la coalici\u00f3n tarsiana provocar complicaciones a largo plazo si no se trata?<\/strong><br\/>Un. Si no se trata, la coalici\u00f3n tarsiana puede provocar dolor cr\u00f3nico, degeneraci\u00f3n articular y p\u00e9rdida de funci\u00f3n del pie.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Q. \u00bfEs \u00fatil la fisioterapia para gestionar la coalici\u00f3n tarsal?<\/strong><br\/>Un. S\u00ed, la fisioterapia puede ayudar a mejorar la movilidad de los pies, fortalecer los m\u00fasculos y reducir el dolor.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Q. \u00bfPuede una persona con coalici\u00f3n tarsiana seguir practicando deportes?<\/strong><br\/>Un. Algunas personas pueden continuar con el deporte con el tratamiento adecuado, pero otras pueden necesitar limitar o modificar la actividad en funci\u00f3n del dolor y la rigidez.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Q. \u00bfEs siempre dolorosa la coalici\u00f3n tarsana?<\/strong><br\/>R. No. Hasta el 75% de las personas con coalici\u00f3n son asintom\u00e1ticas, y la condici\u00f3n puede encontrarse solo de forma incidental. <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Q. \u00bfPueden los ni\u00f1os superar la coalici\u00f3n tarsal?<\/strong><br\/>R. No, la coalici\u00f3n no desaparece, pero un tratamiento temprano puede prevenir deformidades a largo plazo.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Q. \u00bfSe pueden afectar ambos pies?<\/strong><br\/>S\u00ed, aproximadamente la mitad de los pacientes tienen coaliciones bilaterales.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Q. \u00bfPodr\u00e9 volver a practicar deportes?<\/strong><br\/>Un. La mayor\u00eda de los pacientes vuelven al deporte tras una recuperaci\u00f3n completa, especialmente si la coalici\u00f3n se reseca con \u00e9xito y la rehabilitaci\u00f3n se sigue de cerca.<\/p>\n\n<h3 class=\"wp-block-heading\">Resumen y conclusiones<\/h3>\n\n<p class=\"wp-block-paragraph\">La coalici\u00f3n tarsiana es una conexi\u00f3n anormal entre dos o m\u00e1s huesos del pie que limita el movimiento y puede causar el pie plano, rigidez y esguinces recurrentes. Normalmente se desarrolla durante el crecimiento fetal, pero se vuelve sintom\u00e1tico en la adolescencia. El diagn\u00f3stico se realiza mediante radiograf\u00edas, TAC o resonancia magn\u00e9tica. El tratamiento comienza con cuidados conservadores, que incluyen reposo, ortesis y medicamentos antiinflamatorios, aunque puede ser necesaria cirug\u00eda por dolor persistente o deformidad. Con un tratamiento adecuado, la mayor\u00eda de los pacientes recuperan la movilidad y vuelven a la actividad normal.    <\/p>\n\n<h3 class=\"wp-block-heading\">Perspectiva cl\u00ednica y hallazgos recientes<\/h3>\n\n<p class=\"wp-block-paragraph\">Un estudio reciente publicado en el <em>HSS Journal\u00ae<\/em> examin\u00f3 la coalici\u00f3n tarsiana en atletas adolescentes, destacando su impacto en la biomec\u00e1nica del pie y el rendimiento deportivo. La condici\u00f3n, que ocurre cuando dos o m\u00e1s huesos tarsianos se fusionan de forma anormal, puede provocar dolor, rigidez, inestabilidad y esguinces recurrentes debido a la restringida movilidad subtalar. <\/p>\n\n<p class=\"wp-block-paragraph\">Aunque los casos leves pueden tratarse con reposo, ortesis o fisioterapia, la mayor\u00eda de los deportistas con s\u00edntomas acaban necesitando cirug\u00eda. El estudio encontr\u00f3 que la resecci\u00f3n quir\u00fargica abierta con interposici\u00f3n de injertos de grasa sigue siendo el est\u00e1ndar de oro, ofreciendo alivio del dolor, restauraci\u00f3n del movimiento y prevenci\u00f3n de recurrencias. <\/p>\n\n<p class=\"wp-block-paragraph\">Las tasas de \u00e9xito generales tras el tratamiento quir\u00fargico superaron el 80%, con bajas tasas de complicaciones y altas tasas de retorno al deporte, especialmente cuando tanto el tipo de coalici\u00f3n como la alineaci\u00f3n del pie se evaluaban cuidadosamente antes de la cirug\u00eda. (&#8220;<em><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/39108448\/\" target=\"_blank\" rel=\"noreferrer noopener\">Estudio sobre el manejo quir\u00fargico de la coalici\u00f3n tarsiana en j\u00f3venes atletas \u2013 v\u00e9ase PubMed.<\/a>&#8220;)<\/em> <\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfQui\u00e9n realiza este tratamiento? (Especialistas y equipo implicado) <\/h3>\n\n<p class=\"wp-block-paragraph\">El tratamiento lo realiza un cirujano ortop\u00e9dico de pie y tobillo o un cirujano pod\u00f3logo. El equipo de atenci\u00f3n puede incluir radi\u00f3logos, anestesi\u00f3logos y fisioterapeutas que ayudan en el diagn\u00f3stico, la cirug\u00eda y la rehabilitaci\u00f3n. <\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfCu\u00e1ndo acudir a un especialista?<\/h3>\n\n<p class=\"wp-block-paragraph\">Deber\u00edas acudir a un especialista si t\u00fa o tu hijo experiment\u00e1is dolor persistente en los pies, rigidez, esguinces frecuentes o pies planos que no mejoran con calzado que le den soporte.<\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfCu\u00e1ndo acudir a urgencias?<\/h3>\n\n<p class=\"wp-block-paragraph\">Acude a urgencias si tienes dolor intenso tras una lesi\u00f3n, incapacidad para soportar peso, deformidad visible o signos de infecci\u00f3n como enrojecimiento, hinchaz\u00f3n y fiebre.<\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfC\u00f3mo es realmente la recuperaci\u00f3n?<\/h3>\n\n<p class=\"wp-block-paragraph\">La recuperaci\u00f3n puede incluir varias semanas de reposo, seguidas de una rehabilitaci\u00f3n gradual. Al principio puede persistir una leve rigidez o molestia, pero la mayor\u00eda de los pacientes recuperan la movilidad casi normal. La fisioterapia constante y el calzado adecuado son clave para obtener resultados \u00f3ptimos.  <\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 ocurre si lo ignoras?<\/h3>\n\n<p class=\"wp-block-paragraph\">La coalici\u00f3n tarsiana no tratada puede provocar deformidades progresivas en el pie plano, dolor cr\u00f3nico, artritis y movilidad reducida. El diagn\u00f3stico precoz previene da\u00f1os y deformidades articulares a largo plazo. <\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfC\u00f3mo prevenirlo?<\/h3>\n\n<p class=\"wp-block-paragraph\">Aunque las coaliciones cong\u00e9nitas no pueden evitarse, el calzado adecuado, mantener un peso saludable y una evaluaci\u00f3n m\u00e9dica temprana para el dolor recurrente en el tobillo pueden reducir complicaciones y deformidades.<\/p>\n\n<h3 class=\"wp-block-heading\">Nutrici\u00f3n y salud \u00f3sea o articular<\/h3>\n\n<p class=\"wp-block-paragraph\">Una dieta equilibrada, rica en calcio, vitamina D y prote\u00ednas, favorece el desarrollo y la curaci\u00f3n \u00f3sea tras el tratamiento. Evitar fumar y mantener una buena hidrataci\u00f3n tambi\u00e9n ayuda a la recuperaci\u00f3n. <\/p>\n\n<h3 class=\"wp-block-heading\">Modificaciones de la actividad y del estilo de vida<\/h3>\n\n<p class=\"wp-block-paragraph\">Tras el tratamiento, los pacientes deben volver gradualmente a las actividades. Se recomiendan ejercicios de bajo impacto como el ciclismo, la nataci\u00f3n o el yoga. Los zapatos y plantillas ortop\u00e9dicas que den soporte pueden proteger el pie del estr\u00e9s excesivo y ayudar a prevenir la recurrencia del dolor o la rigidez.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La coalici\u00f3n tarsiana es una afecci\u00f3n en la que dos o m\u00e1s huesos en la parte posterior del pie (los huesos tarsianos) est\u00e1n conectados de forma anormal. Esta conexi\u00f3n puede estar formada por hueso, cart\u00edlago o tejido fibroso. Mientras que algunas personas nunca experimentan s\u00edntomas, otras pueden desarrollar dolor, rigidez o deformidad en el pie [&hellip;]<\/p>\n","protected":false},"featured_media":67896,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Coalici\u00f3n Tarsal - Ortopedia y Podolog\u00eda Completa | M\u00faltiples ubicaciones en Nueva York","_seopress_titles_desc":"La coalici\u00f3n tarsiana es una afecci\u00f3n en la que dos o m\u00e1s huesos en la parte posterior del pie (los huesos tarsianos) est\u00e1n conectados de forma anormal. Esta conexi\u00f3n puede estar formada por hueso, cart\u00edlago o tejido fibroso. Mientras que algunas personas nunca experimentan s\u00edntomas, otras pueden desarrollar dolor, rigidez o deformidad en el pie plano a medida que crecen...  ","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"service-tags":[141],"special-treatment":[],"service-categories":[152],"class_list":["post-69191","service","type-service","status-publish","has-post-thumbnail","hentry","service-tags-condicion","service-categories-pie-y-tobillo"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/service\/69191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/service"}],"about":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/types\/service"}],"version-history":[{"count":1,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/service\/69191\/revisions"}],"predecessor-version":[{"id":69194,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/service\/69191\/revisions\/69194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/media\/67896"}],"wp:attachment":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/media?parent=69191"}],"wp:term":[{"taxonomy":"service-tags","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/service-tags?post=69191"},{"taxonomy":"special-treatment","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/special-treatment?post=69191"},{"taxonomy":"service-categories","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/service-categories?post=69191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}