{"id":202,"count":5,"description":"","link":"https:\/\/www.cortho.org\/es\/categorias-de-preguntas-frecuentes\/hombro\/","name":"hombro","slug":"hombro","taxonomy":"faq-categrories","parent":0,"meta":[],"acf":[],"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/faq-categrories\/202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/faq-categrories"}],"about":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/taxonomies\/faq-categrories"}],"wp:post_type":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/faq?faq-categrories=202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}