{"id":70001,"date":"2025-10-18T11:42:21","date_gmt":"2025-10-18T11:42:21","guid":{"rendered":"https:\/\/cortho.org\/case-studies\/estudio-de-caso-rodilla-operativa-basica-meniscectomia-parcial-artroscopica-y-condroplastia-medial\/"},"modified":"2026-01-03T09:45:45","modified_gmt":"2026-01-03T09:45:45","slug":"estudio-de-caso-rodilla-operativa-basica-meniscectomia-parcial-artroscopica-y-condroplastia-medial","status":"publish","type":"case-studies","link":"https:\/\/www.cortho.org\/es\/estudios-de-caso\/estudios-de-casos-de-medicina-deportiva\/estudio-de-caso-rodilla-operativa-basica-meniscectomia-parcial-artroscopica-y-condroplastia-medial\/","title":{"rendered":"Estudio de caso: Rodilla operativa b\u00e1sica: Meniscectom\u00eda parcial artrosc\u00f3pica y condroplastia medial"},"content":{"rendered":"\n<p><a href=\"\/knee\/knee-pain\/\">El dolor de rodilla<\/a> es una afecci\u00f3n com\u00fan que afecta a personas de todas las edades y puede ser causada por una lesi\u00f3n como la rotura de un ligamento o un desgarro de cart\u00edlago. El dolor en la rodilla tambi\u00e9n puede ser causado por condiciones m\u00e9dicas como artritis, gota e infecciones. <\/p>\n\n<p>La paciente es una mujer de 43 a\u00f1os que presenta quejas de dolor en la rodilla derecha durante m\u00e1s de un mes. El paciente recuerda la lesi\u00f3n en ambas rodillas en un accidente de coche hace 3 a\u00f1os. El dolor es de intensidad moderada a intensa. El paciente describe el dolor como sordo, punzante, punzante. El dolor es constante y s\u00ed interrumpe el sue\u00f1o.    <\/p>\n\n<p>El dolor est\u00e1 asociado a hinchaz\u00f3n, chasquidos al suelo. El problema ha ido empeorando desde que empez\u00f3. Caminar, estar de pie, levantar pesas, hacer ejercicio, girar, doblarse, agacharse, arrodillarse y escalar empeoran los s\u00edntomas. Descansar, el celo y tumbarse mejoran los s\u00edntomas.   <\/p>\n\n<p>Al examinar la rodilla derecha, el paciente es sensible a la palpaci\u00f3n a lo largo de la l\u00ednea articular medial y sufre un derrame. Hay dolor a lo largo de la l\u00ednea de la articulaci\u00f3n fascite plantar medial y lateral. El paciente siente molestias con las maniobras de McMurray y la rodilla est\u00e1 estable.  <\/p>\n\n<p>No tienen flexi\u00f3n completa secundaria al derrame, pero s\u00ed tienen extensi\u00f3n total. Tienen una fuerza de 5\/5 y est\u00e1n neurovascularmente intactas distalmente. No hay eritema, calor ni lesiones cut\u00e1neas presentes.  <\/p>\n\n<p>Se realizaron radiograf\u00edas y resonancias magn\u00e9ticas en la consulta. Se encontr\u00f3 desgarro vertical en el borde libre del menisco medial del cuerno posterior, con un leve deshilachamiento en la parte inferior inferior\/borde libre del segmento corporal. P\u00e9rdida condral leve del compartimento femorotibial medial. Desgaste condral leve del compartimento patelofemoral, preferentemente sobre la parte medial del compartimento.   <\/p>\n\n<p>Inclinaci\u00f3n lateral de la r\u00f3tula con posici\u00f3n lateral leve de la r\u00f3tula. Estos hallazgos pueden observarse en el contexto del trasvase de malta rotuliana. Caracter\u00edsticas que pueden observarse en el contexto del s\u00edndrome de fricci\u00f3n de la banda iliotibial.  <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"153\" height=\"171\" data-src=\"\/wp-content\/uploads\/2023\/06\/Lateral-View.png\" alt=\"Vista lateral\" class=\"wp-image-28637 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 153px; --smush-placeholder-aspect-ratio: 153\/171;\" \/><\/figure>\n<\/div>\n<p class=\"has-text-align-center\"><strong>Vista lateral<\/strong><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"241\" height=\"155\" data-src=\"\/wp-content\/uploads\/2023\/06\/Patella-Skyline.png\" alt=\"Horizonte de Patella\" class=\"wp-image-28639 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 241px; --smush-placeholder-aspect-ratio: 241\/155;\" \/><\/figure>\n<\/div>\n<p class=\"has-text-align-center\"><strong>Horizonte de Patella<\/strong><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"146\" height=\"155\" data-src=\"\/wp-content\/uploads\/2023\/06\/AP-view.png\" alt=\"Opini\u00f3n AP\" class=\"wp-image-28633 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 146px; --smush-placeholder-aspect-ratio: 146\/155;\" \/><\/figure>\n<\/div>\n<p class=\"has-text-align-center\"><strong>Opini\u00f3n AP<\/strong><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img alt=\"\" decoding=\"async\" width=\"407\" height=\"190\" data-src=\"\/wp-content\/uploads\/2023\/06\/image10.png\" alt=\"\" class=\"wp-image-28635 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 407px; --smush-placeholder-aspect-ratio: 407\/190;\" \/><\/figure>\n<\/div>\n<p>Hablamos sobre las opciones de tratamiento para el diagn\u00f3stico del paciente, que inclu\u00edan: vivir con la extremidad tal como est\u00e1, ejercicios organizados, medicamentos, inyecciones y opciones quir\u00fargicas. Tambi\u00e9n discutimos la naturaleza y el prop\u00f3sito de las opciones de tratamiento, as\u00ed como los riesgos y beneficios esperados. El paciente ha expresado su deseo de proceder con la cirug\u00eda.<\/p>\n\n<p>Hablamos sobre las opciones de tratamiento y el paciente opt\u00f3 por el manejo quir\u00fargico. Hablamos sobre los riesgos y beneficios de la cirug\u00eda, incluido el sangrado. infecci\u00f3n, <a href=\"https:\/\/www.cortho.org\/es\/rodilla\/condiciones\/rigidez-tras-una-protesis-de-rodilla\/attachment\/stiffness-after-knee-replacement-3\/\">rigidez de rodilla<\/a>, re-desgarro, necesidad de repetir cirug\u00eda, necesidad de rehabilitaci\u00f3n, ausencia de lesi\u00f3n en nervios y vasos adyacentes. El paciente comprendi\u00f3 bien los riesgos, beneficios y complicaciones y firm\u00f3 un consentimiento informado.  <\/p>\n\n<p>Se indujo anestesia general en el paciente y se prepar\u00f3 la extremidad inferior derecha tras la aplicaci\u00f3n del torniquete y Esmarch. La extremidad inferior derecha estaba colgada de forma as\u00e9ptica. <\/p>\n\n<p>Se realiz\u00f3 una incisi\u00f3n lateral en la puerta de entrada. Se introdujo el artroscopio. El endoscopio se traslad\u00f3 al compartimento tibiofemoral medial, donde se realiz\u00f3 un portal de entrada medial utilizando una aguja espinal.  <\/p>\n\n<p>Se introdujo una sonda. Se observ\u00f3 la <a href=\"https:\/\/www.cortho.org\/es\/service\/menisco-de-rodilla\/\">rotura del menisco<\/a> medial atravesando el cuerpo y el cuerno posterior hasta la ra\u00edz. Se introdujo la afeitadora y se limpiaron los m\u00e1rgenes. Se usaron el mordedor ascendente y el mordedor recto para eliminar el menisco degenerado a lo largo del borde interior del menisco medial. El endoscopio se traslad\u00f3 a la muesca intercondilar, donde se encontr\u00f3 que el <a href=\"https:\/\/www.cortho.org\/es\/knee\/ligamento-cruzado-anterior\/\">LCA<\/a> estaba intacto con degeneraci\u00f3n.    <\/p>\n\n<p>El endoscopio se traslad\u00f3 nuevamente a la articulaci\u00f3n patelofemoral, donde se encontr\u00f3 una lesi\u00f3n de grado 3 a 4 de OA en el c\u00f3ndilo tibiofemoral medial en la regi\u00f3n correspondiente. Se limpiaba con un mordador y una afeitadora. Se volvi\u00f3 a examinar la rodilla y se desbrid\u00f3 a\u00fan m\u00e1s el menisco medial.  <\/p>\n\n<p>Tambi\u00e9n se afeit\u00f3 la lesi\u00f3n condral del c\u00f3ndilo femoral medial. La rodilla estaba abundantemente irrigada. Se retir\u00f3 el telescopio. Las incisiones se cerraron con nylon #3-0. Se inyectaron 20 cc de Marca\u00edna 0,5\u00b0\/4 en la rodilla.    <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img alt=\"\" decoding=\"async\" width=\"596\" height=\"309\" data-src=\"\/wp-content\/uploads\/2023\/06\/Untitled-design-1.png\" alt=\"\" class=\"wp-image-28643 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 596px; --smush-placeholder-aspect-ratio: 596\/309;\" \/><\/figure>\n<\/div>\n<p>Tras una semana de operaci\u00f3n, se atendi\u00f3 a una paciente en la consulta, caminaba con poca molestia. Niega fiebre, escalofr\u00edos. Al examinar la rodilla derecha, se revela que hay un peque\u00f1o derrame. Las incisiones est\u00e1n cicatrizando bien, sin indicios de drenaje, eritema o calor.   <\/p>\n\n<p>El rango de movimiento es limitado como consecuencia de la incomodidad. La fuerza distal es 5\/5. No hay sensibilidad en la pantorrilla ni un signo de Homan negativo. La sensibilidad se mantiene intacta al tacto ligero distalmente y hay un r\u00e1pido relleno capilar.   <\/p>\n\n<p>Tras discutir las opciones de tratamiento y los riesgos de la inyecci\u00f3n, el paciente quiso proceder con la inyecci\u00f3n para reducir el dolor y la hinchaz\u00f3n.<\/p>\n\n<p>Tras una preparaci\u00f3n est\u00e9ril, se inyectaron 3 cc de ropivaca\u00edna al 1%, 3 cc de marca\u00edna al 0,5% y 80 mg de depo-Medrol en la rodilla derecha. El paciente toler\u00f3 bien el procedimiento y no hubo complicaciones. <\/p>\n\n<p>Se discutieron en detalle el dolor post-inyecci\u00f3n, el aumento de la glucosa en sangre, la decoloraci\u00f3n de la piel, la atrofia grasa y los signos de infecci\u00f3n. El paciente volv\u00eda a la cl\u00ednica cada 3-4 semanas. El paciente<a href=\"\/faq\/knee\/post-operative-knee-arthroscopy\/\"> se recuper\u00f3 bien de la cirug\u00eda<\/a> y continu\u00f3 su rehabilitaci\u00f3n f\u00edsica.  <\/p>\n\n<p><em>Aviso legal \u2013 El nombre, edad, sexo, fechas y eventos del paciente han sido modificados o modificados para proteger su privacidad.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El dolor de rodilla es una afecci\u00f3n com\u00fan que afecta a personas de todas las edades y puede ser causada por una lesi\u00f3n como la rotura de un ligamento o un desgarro de cart\u00edlago. El dolor en la rodilla tambi\u00e9n puede ser causado por condiciones m\u00e9dicas como artritis, gota e infecciones. La paciente es una [&hellip;]<\/p>\n","protected":false},"featured_media":70002,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Rodilla operativa y condroplastia | Ortopedia Completa","_seopress_titles_desc":"Otro estudio de caso trata sobre Rodilla Operativa B\u00e1sica: Meniscectom\u00eda y Condroplastia Parcial Artrosc\u00f3pica de Complete Orthopedics con m\u00faltiples ubicaciones en Nueva York.","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"case-study-categories":[176],"case-study-tags":[],"class_list":["post-70001","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case-study-categories-estudios-de-casos-de-medicina-deportiva"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-studies\/70001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/media\/70002"}],"wp:attachment":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/media?parent=70001"}],"wp:term":[{"taxonomy":"case-study-categories","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-study-categories?post=70001"},{"taxonomy":"case-study-tags","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-study-tags?post=70001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}