{"id":69884,"date":"2025-10-18T12:44:46","date_gmt":"2025-10-18T12:44:46","guid":{"rendered":"https:\/\/cortho.org\/case-studies\/estudio-de-caso-artroscopia-de-rodilla-meniscectomia-lateral-y-condroplastia-de-la-rotula-y-condilo-femoral-medial-en-una-mujer-de-34-anos\/"},"modified":"2026-02-04T19:13:45","modified_gmt":"2026-02-04T19:13:45","slug":"estudio-de-caso-artroscopia-de-rodilla-meniscectomia-lateral-y-condroplastia-de-la-rotula-y-condilo-femoral-medial-en-una-mujer-de-34-anos","status":"publish","type":"case-studies","link":"https:\/\/www.cortho.org\/es\/estudios-de-caso\/estudio-de-caso-artroscopia-de-rodilla-meniscectomia-lateral-y-condroplastia-de-la-rotula-y-condilo-femoral-medial-en-una-mujer-de-34-anos\/","title":{"rendered":"Estudio de caso: Artroscopia de rodilla: meniscectom\u00eda lateral y condroplastia de la r\u00f3tula y c\u00f3ndilo femoral medial en una mujer de 34 a\u00f1os"},"content":{"rendered":"\n<p>Para tratar las fracturas de r\u00f3tula, que son lesiones frecuentes pero devastadoras, los pacientes suelen ser inmovilizados o, en circunstancias raras, someterse a cirug\u00eda. Los huesos de la rodilla pueden dislocarse. Un impacto a alta velocidad, una ca\u00edda o un accidente pueden causar esto.  <\/p>\n\n<p>Una de las posibles formas a\u00fan inciertas es someterse a una cirug\u00eda. Durante una artroscopia de rodilla, un cirujano utiliza un peque\u00f1o instrumento llamado artroscopio para examinar y tratar problemas. Es un tipo de cirug\u00eda menos intrusiva utilizada para identificar y tratar problemas articulares.  <\/p>\n\n<p>Un paciente de 34 a\u00f1os estaba en nuestra consulta, con quejas de dolor en la rodilla izquierda. La paciente fue a urgencias para volver a colocar la rodilla en la cavidad, dijo que sali\u00f3 de urgencias, ya no hab\u00eda dolor. Dijo que sol\u00eda volver a colocar la rodilla en su sitio, ella sola.  <\/p>\n\n<p>El paciente describe el dolor como agudo, sordo, punzante y palpitante. El dolor est\u00e1 asociado a inflamaci\u00f3n, hematomas, entumecimiento, hormigueo y dolor irradiado, pero no est\u00e1 asociado a debilidad, anomal\u00edas intestinales o vesicales, problemas de marcha, cesi\u00f3n o cojera, ni dificultad en la funci\u00f3n de la mano. <\/p>\n\n<p>Sin embargo, doblarse empeora los s\u00edntomas. Usar un movilizador de rodilla mejora los s\u00edntomas. La paciente ha sido operada de rodilla izquierda, t\u00fanel carpiano y ces\u00e1rea. El paciente no fuma. Trabaja en servicios de limpieza y actualmente no puede trabajar sin un dolor considerable.    <\/p>\n\n<p>Al examinar la rodilla izquierda, el paciente no tiene sensibilidad a la palpaci\u00f3n a lo largo de las l\u00edneas articulares medial y lateral y presenta un derrame leve. Son sensibles a la palpaci\u00f3n a lo largo de la parte medial de la r\u00f3tula y <a href=\"https:\/\/www.cortho.org\/es\/servicio\/reconstruccion-del-ligamento-patelofemoral-medial\/\">del ligamento patelofemoral medial<\/a>. <\/p>\n\n<p>No tienen crepitaci\u00f3n en la articulaci\u00f3n patelofemoral ni rango de movimiento, pero son reticentes a las pruebas de planeo rotuliano. El paciente no siente molestias con las maniobras de McMurray y la rodilla es estable. Tienen un rango de movimiento limitado.  <\/p>\n\n<p>Tienen una fuerza de 5\/5 y est\u00e1n neurovascularmente intactos a nivel distal. No hay eritema, calor ni lesiones cut\u00e1neas presentes. Al examinar la extremidad contralateral, el paciente no tiene sensibilidad a la palpaci\u00f3n y tiene un excelente rango de movimiento, estabilidad y fuerza.<\/p>\n\n<p>Se presentaron los resultados de la resonancia magn\u00e9tica y se mostr\u00f3 una visualizaci\u00f3n de un solo corte de una peque\u00f1a rotura del menisco medial. Derrame articular traza. El LCA no es nada destacable, sin indicios de desgarro, degeneraci\u00f3n o cambio postoperatorio.  <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"289\" height=\"135\" data-src=\"\/wp-content\/uploads\/2023\/06\/MRI-3-T-Left-Knee-Non-contrast.png\" alt=\"Resonancia magn\u00e9tica -3 T rodilla izquierda sin contraste\" class=\"wp-image-28350 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 289px; --smush-placeholder-aspect-ratio: 289\/135;\" \/><\/figure>\n<\/div>\n<p class=\"has-text-align-center\"><strong>Resonancia magn\u00e9tica -3 T rodilla izquierda sin contraste<\/strong><\/p>\n\n<p>Hablamos sobre las opciones de tratamiento para el diagn\u00f3stico del paciente, que inclu\u00edan: vivir con la extremidad tal cual, ejercicios organizados, medicamentos, inyecciones y opciones quir\u00fargicas. Tambi\u00e9n discutimos la naturaleza y el prop\u00f3sito de las opciones de tratamiento, as\u00ed como los riesgos y beneficios esperados.<\/p>\n\n<p>El paciente ha expresado su deseo de proceder con la cirug\u00eda. Inform\u00e9 al paciente sobre los riesgos inherentes e inevitables que incluyen, pero no se limitan a, anestesia, infecciones, da\u00f1os en nervios y vasos sangu\u00edneos, p\u00e9rdida de sangre, co\u00e1gulos e incluso la muerte, que se discutieron en detalle.<\/p>\n\n<p>Tambi\u00e9n hablamos sobre la posibilidad de no poder volver a actividades o empleos anteriores, la necesidad de cirug\u00edas futuras y el s\u00edndrome de dolor regional complejo.<\/p>\n\n<p>Entiendo que suele seguir a la cirug\u00eda un proceso de rehabilitaci\u00f3n largo, y la posibilidad de no poder aliviar todas las molestias. Adem\u00e1s, expliqu\u00e9 que no hay garant\u00eda de que toda la funci\u00f3n y la resistencia vuelvan a funcionar.<\/p>\n\n<p>El paciente tambi\u00e9n comprende los riesgos de una nueva rotura o de no curar. El paciente expres\u00f3 comprensi\u00f3n de estos riesgos y ha decidido proceder con la cirug\u00eda. Hemos hablado del procedimiento quir\u00fargico as\u00ed como de las expectativas realistas respecto a los riesgos, los resultados y el protocolo postoperatorio.<\/p>\n\n<p>La paciente fue llevada al quir\u00f3fano, donde la colocaron sobre una mesa de operaciones bien acolchada. Se indujo anestesia general. <\/p>\n\n<p>La extremidad inferior izquierda estaba preparada y colocada de forma as\u00e9ptica. Se administr\u00f3 antibi\u00f3tico preoperatorio. Se realiz\u00f3 un portal de entrada lateral para el examen artrosc\u00f3pico. Se insert\u00f3 el artroscopio.   <\/p>\n\n<p>Hab\u00eda una peque\u00f1a zona de artritis de grado 2 a 3 en la zona de la r\u00f3tula medial, que fue limpiada. El examen de la muesca intercondilar estaba intacta del LCA. Examen del menisco marginal medial de la articulaci\u00f3n tibiofemoral, que fue limpiado con afeitadora y albores ascendentes. No hab\u00eda desgarro en el menisco medial.   <\/p>\n\n<p>Hubo una gran pausa popl\u00edtea con la posible ruptura en el cuerno posterior del menisco lateral, que estaba incompleto. Se realiz\u00f3 un examen exhaustivo y se realiz\u00f3 el desbridamiento. Se decidi\u00f3 no repararlo por el momento porque parec\u00eda ser una pausa extensiva del popl\u00edteo.  <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"437\" height=\"176\" data-src=\"\/wp-content\/uploads\/2023\/06\/Intraoperative-Arthroscopy-Images.png\" alt=\"Im\u00e1genes de artroscopia intraoperatoria\" class=\"wp-image-28348 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 437px; --smush-placeholder-aspect-ratio: 437\/176;\" \/><\/figure>\n<\/div>\n<p class=\"has-text-align-center\"><strong>Im\u00e1genes de artroscopia intraoperatoria<\/strong><\/p>\n\n<p>Ahora se retir\u00f3 el endoscopio y se realiz\u00f3 una incisi\u00f3n medial sobre el margen superior medial de la r\u00f3tula. El tend\u00f3n qued\u00f3 expuesto y limpio. Se pasaron dos cables gu\u00eda bajo el brazo C. <\/p>\n\n<p>El escariado se hizo sobre el cable gu\u00eda y se coloc\u00f3 para el SwiveLock. Se pas\u00f3 otro cable gu\u00eda en la r\u00f3tula a unos 15 mm de distal. Tambi\u00e9n se interpret\u00f3 el resto.  <\/p>\n\n<p>El extremo libre del tend\u00f3n se insertaba en la r\u00f3tula en los orificios superior e inferior usando SwiveLock. Ahora el punto femoral se localiz\u00f3 usando una gu\u00eda y se hizo una incisi\u00f3n tras comprobar bajo el brazo en C. Se lleg\u00f3 a la disecci\u00f3n.  <\/p>\n\n<p>Se coloc\u00f3 de nuevo un cable gu\u00eda y se comprob\u00f3 bajo el brazo en C, y se comprob\u00f3 que estaba en la posici\u00f3n adecuada. Se coloc\u00f3 en el f\u00e9mur y desde la direcci\u00f3n medial inferior hasta posterior superior. <\/p>\n\n<p>La disecci\u00f3n se realiz\u00f3 entre la segunda y tercera capa de la rodilla medial en la r\u00f3tula y la am\u00edgdala se redujo y se pas\u00f3 al sitio femoral.<\/p>\n\n<p>La sutura se pasaba de vuelta desde ah\u00ed y el tend\u00f3n se pasaba de nuevo al sitio femoral para ser entregado. Se at\u00f3 alrededor del alambre y se comprob\u00f3 que estaba en una posici\u00f3n aceptable, atada en flexi\u00f3n de 30 grados y aflojada en 90 grados de flexi\u00f3n y extensi\u00f3n. Se realiz\u00f3 un escariado. El pin de Beath se pas\u00f3 de un lado a otro.   <\/p>\n\n<p>El escariado se realizaba desde 40 mm sobre el pin Beath. Las suturas a trav\u00e9s del lazo tendinoso pasaban por el pasador Beath y se distribu\u00edan lateralmente. Se aplic\u00f3 una tensi\u00f3n adecuada para no apretar demasiado la r\u00f3tula con 30 grados de flexi\u00f3n y la excisi\u00f3n del tend\u00f3n se realiz\u00f3 con tornillo de interferencia. Se revis\u00f3 el tend\u00f3n final y se consider\u00f3 satisfactorio.   <\/p>\n\n<p>Se retiraron las suturas y las suturas de r\u00f3tula se usaron para refuerzo y corte. El cierre de la herida se realiz\u00f3 tras el riego en capas. Monocryl se us\u00f3 para cerrar el ciclo. El aderezo se hizo usando 4 x 4, ABD, Webril y Ace wrap. Se aplic\u00f3 una f\u00e9rula de Bledsoe y se extendi\u00f3 en extensi\u00f3n.    <\/p>\n\n<p>El paciente fue extubado. La anestesia le aplic\u00f3 un bloqueo del canal femoral para aliviar el dolor. La paciente fue informada antes de la operaci\u00f3n sobre eso, as\u00ed como sobre la lesi\u00f3n \u00f3ptima de su madre, sobre las precauciones y el uso de la f\u00e9rula. Los pacientes pidieron usar la medicaci\u00f3n, el hielo y la elevaci\u00f3n.   <\/p>\n\n<p>El paciente fue <a href=\"\/faq\/knee\/post-operative-knee-arthroscopy\/\">atendido para un chequeo postoperatorio<\/a>. Hemos decidido realizar fisioterapia formal as\u00ed como un programa de ejercicios en casa para la rehabilitaci\u00f3n de la rodilla.  El paciente segu\u00eda regularmente una visita a la consulta cada 3-4 semanas.<\/p>\n\n<p>El paciente se recuper\u00f3 bien tras la cirug\u00eda y continu\u00f3 la fisioterapia. La paciente se registr\u00f3 para visitas de seguimiento despu\u00e9s de un mes y not\u00f3 una mejora significativa en la rodilla.<\/p>\n\n<p><em>Aviso legal \u2013 El nombre, edad, sexo, fechas y eventos del paciente han sido modificados o modificados para proteger su privacidad.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para tratar las fracturas de r\u00f3tula, que son lesiones frecuentes pero devastadoras, los pacientes suelen ser inmovilizados o, en circunstancias raras, someterse a cirug\u00eda. Los huesos de la rodilla pueden dislocarse. Un impacto a alta velocidad, una ca\u00edda o un accidente pueden causar esto. Una de las posibles formas a\u00fan inciertas es someterse a una [&hellip;]<\/p>\n","protected":false},"featured_media":69885,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Estudio de caso: Artroscopia de rodilla: meniscectom\u00eda lateral y condroplastia de la r\u00f3tula y c\u00f3ndilo femoral medial en una mujer de 34 a\u00f1os | Ortopedia Completa | NY","_seopress_titles_desc":"Estudio de caso: Artroscopia de rodilla: meniscectom\u00eda lateral y condroplastia de la r\u00f3tula y c\u00f3ndilo femoral medial en una mujer de 34 a\u00f1os de Complete Orthopedics.","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"case-study-categories":[176],"case-study-tags":[],"class_list":["post-69884","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case-study-categories-estudios-de-casos-de-medicina-deportiva"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-studies\/69884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/media\/69885"}],"wp:attachment":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/media?parent=69884"}],"wp:term":[{"taxonomy":"case-study-categories","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-study-categories?post=69884"},{"taxonomy":"case-study-tags","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-study-tags?post=69884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}