{"id":69872,"date":"2025-10-18T12:29:42","date_gmt":"2025-10-18T12:29:42","guid":{"rendered":"https:\/\/cortho.org\/case-studies\/estudio-de-caso-tecnica-fluoroscopica-reduccion-abierta-y-fijacion-interna-usando-placa-y-tornillos-en-un-hombre-de-59-anos\/"},"modified":"2026-01-03T09:19:00","modified_gmt":"2026-01-03T09:19:00","slug":"estudio-de-caso-tecnica-fluoroscopica-reduccion-abierta-y-fijacion-interna-usando-placa-y-tornillos-en-un-hombre-de-59-anos","status":"publish","type":"case-studies","link":"https:\/\/www.cortho.org\/es\/estudios-de-caso\/estudios-de-casos-de-medicina-deportiva\/estudio-de-caso-tecnica-fluoroscopica-reduccion-abierta-y-fijacion-interna-usando-placa-y-tornillos-en-un-hombre-de-59-anos\/","title":{"rendered":"Estudio de caso: T\u00e9cnica fluorosc\u00f3pica: reducci\u00f3n abierta y fijaci\u00f3n interna usando placa y tornillos en un hombre de 59 a\u00f1os"},"content":{"rendered":"\n<p>Una reducci\u00f3n abierta y fijaci\u00f3n interna (ORIF) son procedimientos quir\u00fargicos que reposicionan fragmentos \u00f3seos fragmentados. Para mantener unido el hueso da\u00f1ado, se emplean tornillos, placas, suturas o varillas. Es un procedimiento que se utiliza para apoyar y reparar un hueso da\u00f1ado.  <\/p>\n\n<p>Un paciente masculino de 59 a\u00f1os visita la consulta quej\u00e1ndose de su dolor en el tobillo derecho debido a una ca\u00edda durante unas dos semanas. Su pierna derecha cay\u00f3 en un agujero en el suelo y se torci\u00f3. Durante las visitas, acordamos hacerle un TAC para averiguar qu\u00e9 causaba el dolor de su tobillo derecho.  <\/p>\n\n<p>TAC presentado y revisado; Los huesos normalmente se mineralizan sin una lesi\u00f3n \u00f3sea focal. Existe una fractura no unida y orientada oblicuamente de la metadi\u00e1fisis distal, que se extiende hasta el nivel de la sindesmosis inferior, justo proximal al techo tibial. <\/p>\n\n<p>El fragmento de fractura distal mide 4 cm de longitud y est\u00e1 ligeramente desplazado hacia atr\u00e1s y lateralmente menos de 2 mm. No hay angulaci\u00f3n significativa. No se observan otras fracturas. Hay un gran os trigono posterior al t\u00e1galo con cambios degenerativos en la sincrondrosis.   <\/p>\n\n<p>La mortaja del tobillo no est\u00e1 ensanchada. La c\u00fapula t\u00e1lar es lisa y no presenta una lesi\u00f3n osteocondral. No hay estrechamiento del espacio articular tibiotalar. Se observan calcificaciones tenues a lo largo de los ligamentos laterales y dentro del receso articular lateral.   <\/p>\n\n<p>Condrocalcinosis leve. No hay derrame articular. La TC es sub\u00f3ptima para evaluar los complejos ligamentosos del tobillo.  <\/p>\n\n<p>Existe un leve estrechamiento de las articulaciones subtalares posteriores y talonaviculares. La evaluaci\u00f3n limitada del mediopi\u00e9 no es nada destacable. La evaluaci\u00f3n limitada de los tendones flexores y extensores no es destacable. La sombra del tend\u00f3n de Aquiles es totalmente anodina.   <\/p>\n\n<p>La musculatura no mejorada es normal. Fractura ligeramente desplazada y orientada oblicua de la f\u00edbula distal, que se extiende hasta la sindesmosis inferior, justo proximal al plafond tibial; calcificaciones tenues a lo largo de la regi\u00f3n del receso articular lateral y ligamentoso lateral favorecen una condrocalcinosis leve. <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"609\" height=\"258\" data-src=\"\/wp-content\/uploads\/2023\/07\/CT-Right-ankle-non-contrast.png\" alt=\"TAC Tobillo derecho sin contraste\" class=\"wp-image-32169 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 609px; --smush-placeholder-aspect-ratio: 609\/258;\" \/><\/figure>\n<\/div>\n<p class=\"has-text-align-center\"><strong>TAC Tobillo derecho sin contraste<\/strong><\/p>\n\n<p>Tras el resultado de la tomograf\u00eda, empezamos a discutir las opciones de tratamiento, incluyendo opciones quir\u00fargicas y no quir\u00fargicas. Tambi\u00e9n comentamos los riesgos y beneficios, incluyendo infecci\u00f3n, sangrado, fallo o falta de curaci\u00f3n del implante, necesidad de repetir cirug\u00edas, lesiones en nervios y vasos adyacentes, necesidad de rehabilitaci\u00f3n, dolor de tobillo e inestabilidad. <\/p>\n\n<p>Sin embargo, el paciente opt\u00f3 por el manejo quir\u00fargico. Tambi\u00e9n hablamos de riesgos, beneficios y complicaciones, incluyendo co\u00e1gulos sangu\u00edneos, complicaciones card\u00edacas, neurol\u00f3gicas y pulmonares, incluyendo la muerte.  El paciente entendi\u00f3 y firm\u00f3 su consentimiento informado.<\/p>\n\n<p>El paciente fue llevado al quir\u00f3fano, donde lo colocaron sobre una mesa de quir\u00f3fano bien acolchada. Se aplic\u00f3 torniquete. La extremidad inferior derecha estaba preparada y colocada as\u00e9pticamente de la manera habitual. Se administr\u00f3 antibi\u00f3tico preoperatorio. Se pidi\u00f3 un tiempo muerto.    <\/p>\n\n<p>Se planific\u00f3 una incisi\u00f3n lateral derecha sobre el peron\u00e9 distal. Esa incisi\u00f3n fue realizada. Con una disecci\u00f3n aguda, se alcanz\u00f3 el hueso y la fractura. La fractura fue abierta y lavada. La fractura fue reducida y sujetada con pinzas.    <\/p>\n\n<p>Se utiliz\u00f3 un tornillo interfragmentario de 3,5 mm para comprimir los fragmentos. Una vez terminado, se utilizaba una cinta de conducci\u00f3n lateral media para soportar la fijaci\u00f3n. Se usaban tornillos de bloqueo distal, as\u00ed como proximales, para lograr la fijaci\u00f3n.  <\/p>\n\n<p>Se tomaron fotos intraoperatorias y finales con el C-arm y se guardaron. La herida fue completamente lavada. El cierre se hizo en capas usando #0 Vicryl, # 2-0 Vicryl y Monopril. El vestido estaba hecho. Se retir\u00f3 el torniquete. Se coloc\u00f3 una f\u00e9rula corta en la pierna. El paciente fue extubado y trasladado a recuperaci\u00f3n en estado estable.      <\/p>\n\n<p>Una semana despu\u00e9s de la cirug\u00eda, el paciente acude a la consulta con el resultado de una radiograf\u00eda y se produce una fractura quir\u00fargicamente tratada en la f\u00edbula distal. Las placas de fijaci\u00f3n y varios tornillos est\u00e1n en su sitio. Los fragmentos de fractura est\u00e1n bien posicionados y alineados.  <\/p>\n\n<p>La tibia derecha muestra m\u00e1rgenes corticales intactos sin evidencia de fractura aguda. Los aspectos visualizados del talus derecho, el calcano y los huesos tarsos muestran m\u00e1rgenes corticales intactos sin indicios de fractura aguda. No hay cambios degenerativos significativos.  <\/p>\n\n<p>La mortaisa del tobillo est\u00e1 bien mantenida y no hay hinchaz\u00f3n apreciable de tejidos blandos. No hay espol\u00f3n plantar calc\u00e1neo. Estado tras fractura distal del peron\u00e9 ORIF. Los fragmentos de fractura est\u00e1n bien posicionados y alineados. El paciente est\u00e1 bien tras la cirug\u00eda, elevando y poniendo hielo.    <\/p>\n\n<p>Sigue usando aspirinas como analg\u00e9sicos, niega fiebre, tiene escalofr\u00edos, pero sigue siendo sin apoyar y usando muletas. Tras dos semanas, la piel que se descama sobre la incisi\u00f3n mejora y se realiza el vendaje con bacitracina y la f\u00e9rula debe continuar durante 2 semanas m\u00e1s. Se recomend\u00f3 al paciente durante 2 semanas que la aplicaci\u00f3n de las botas.  <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"577\" height=\"235\" data-src=\"\/wp-content\/uploads\/2023\/07\/X-ray-right-ankle-2-weeks-after-surgery.png\" alt=\"Radiograf\u00eda del tobillo derecho - 2 semanas despu\u00e9s de la cirug\u00eda\" class=\"wp-image-32171 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 577px; --smush-placeholder-aspect-ratio: 577\/235;\" \/><\/figure>\n<\/div>\n<p class=\"has-text-align-center\"><strong>Radiograf\u00eda del tobillo derecho \u2013 2 semanas despu\u00e9s de la cirug\u00eda<\/strong><\/p>\n\n<p>Tras tres semanas de la cirug\u00eda, el paciente fue a la consulta con los resultados de las radiograf\u00edas para su revisi\u00f3n de seguimiento. La piel del paciente que se despega sobre la incisi\u00f3n se resuelve, la bota de caminar PWB 25%, aumentando gradualmente con la ayuda del hielo, la elevaci\u00f3n y los antiinflamatorios de venta libre; el paciente est\u00e1 muy bien tras la cirug\u00eda. <\/p>\n\n<p>La placa y los tornillos quir\u00fargicos fijan una fractura de la f\u00edbula distal derecha. La alineaci\u00f3n es casi anat\u00f3mica, no hay un cambio significativo en el intervalo, la tibia distal est\u00e1 intacta. No hay cambios degenerativos significativos, la mortaja del tobillo est\u00e1 bien mantenida. No hay hinchaz\u00f3n apreciable de tejidos blandos ni espol\u00f3n plantar calc\u00e1neo.   <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"555\" height=\"313\" data-src=\"\/wp-content\/uploads\/2023\/07\/X-ray-right-ankle-3-weeks-after-surgery.png\" alt=\"Radiograf\u00eda del tobillo derecho - 3 semanas despu\u00e9s de la cirug\u00eda\" class=\"wp-image-32173 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 555px; --smush-placeholder-aspect-ratio: 555\/313;\" \/><\/figure>\n<\/div>\n<p class=\"has-text-align-center\"><strong>Radiograf\u00eda del tobillo derecho \u2013 3 semanas despu\u00e9s de la cirug\u00eda<\/strong><\/p>\n\n<p>Con la revisi\u00f3n de seguimiento, el paciente mostr\u00f3 progresos de vez en cuando cuando visita la consulta. Se recupera tras la operaci\u00f3n y con la ayuda de la fisioterapia continua. <\/p>\n\n<p><em>Aviso legal \u2013 El nombre, edad, sexo, fechas y eventos del paciente han sido modificados o modificados para proteger su privacidad.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una reducci\u00f3n abierta y fijaci\u00f3n interna (ORIF) son procedimientos quir\u00fargicos que reposicionan fragmentos \u00f3seos fragmentados. Para mantener unido el hueso da\u00f1ado, se emplean tornillos, placas, suturas o varillas. Es un procedimiento que se utiliza para apoyar y reparar un hueso da\u00f1ado. Un paciente masculino de 59 a\u00f1os visita la consulta quej\u00e1ndose de su dolor en [&hellip;]<\/p>\n","protected":false},"featured_media":69873,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Estudio de caso: T\u00e9cnica fluorosc\u00f3pica | Ortopedia Completa","_seopress_titles_desc":"Otro caso de estudio trata sobre la t\u00e9cnica fluorosc\u00f3pica: reducci\u00f3n abierta y fijaci\u00f3n interna usando placa y tornillos en un hombre de 59 a\u00f1os de Complete Orthopedics NY.","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"case-study-categories":[176],"case-study-tags":[],"class_list":["post-69872","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case-study-categories-estudios-de-casos-de-medicina-deportiva"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-studies\/69872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/media\/69873"}],"wp:attachment":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/media?parent=69872"}],"wp:term":[{"taxonomy":"case-study-categories","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-study-categories?post=69872"},{"taxonomy":"case-study-tags","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-study-tags?post=69872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}