{"id":69785,"date":"2025-10-19T03:58:53","date_gmt":"2025-10-19T03:58:53","guid":{"rendered":"https:\/\/cortho.org\/case-studies\/estudio-de-caso-cirugia-de-rodilla-menisco-medial-en-una-mujer-de-68-anos\/"},"modified":"2026-01-03T09:09:38","modified_gmt":"2026-01-03T09:09:38","slug":"estudio-de-caso-cirugia-de-rodilla-menisco-medial-en-una-mujer-de-68-anos","status":"publish","type":"case-studies","link":"https:\/\/www.cortho.org\/es\/estudios-de-caso\/estudios-de-casos-de-medicina-deportiva\/estudio-de-caso-cirugia-de-rodilla-menisco-medial-en-una-mujer-de-68-anos\/","title":{"rendered":"Estudio de caso: Cirug\u00eda de rodilla: menisco medial en una mujer de 68 a\u00f1os"},"content":{"rendered":"\n<p>Una <a href=\"\/faq\/knee\/meniscus-tear\/\">rotura lateral del menisco<\/a> afecta al cart\u00edlago semicircular que recubre el exterior de la articulaci\u00f3n de la rodilla. A trav\u00e9s de torsi\u00f3n o una lesi\u00f3n traum\u00e1tica, la prueba de McMurray es uno de los ex\u00e1menes principales para lesiones de menisco. Tu rodilla ser\u00e1 flexionada por tu m\u00e9dico antes de enderezarla y rotarla.  <\/p>\n\n<p>Esto pone una rotura de menisco sometida a estr\u00e9s. Si tienes una rotura del menisco, este movimiento puede doler, hacer clic o hacer que la articulaci\u00f3n parezca torpe. rigidez o hinchaz\u00f3n. Dolor, especialmente cuando giras o giras la rodilla. Me cuesta estirar completamente la rodilla. Intentando mover la rodilla y sintiendo que est\u00e1 inm\u00f3vil.     <\/p>\n\n<p>Una paciente de 68 a\u00f1os fue atendida en la consulta con dolor en la rodilla derecha del hospital Mather, le pusieron una rodillera y la derivaron a nosotros. La resonancia magn\u00e9tica fue revisada y comentada por el m\u00e9dico; Desgarro complejo del menisco medial. <\/p>\n\n<p>Esguince leve del LCM superpuesto a cicatrices cr\u00f3nicas. Condromalacia rotuliana moderada y p\u00e9rdida leve de cart\u00edlago en el compartimento medial. Derrame articular moderado.  <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"616\" height=\"247\" data-src=\"\/wp-content\/uploads\/2023\/06\/MRI-Right-Knee-Non-contrast-5.png\" alt=\"Resonancia magn\u00e9tica de rodilla derecha sin contraste\" class=\"wp-image-30976 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 616px; --smush-placeholder-aspect-ratio: 616\/247;\" \/><\/figure>\n<\/div>\n<p class=\"has-text-align-center\"><strong>Resonancia magn\u00e9tica de rodilla derecha sin contraste<\/strong><\/p>\n\n<p>Tras dos d\u00edas, el paciente volvi\u00f3 a la consulta y discutimos las opciones de tratamiento para el diagn\u00f3stico del paciente, que inclu\u00edan: vivir con la extremidad tal cual, ejercicios organizados, medicamentos, inyecciones y opciones quir\u00fargicas. Tambi\u00e9n discutimos la naturaleza y el prop\u00f3sito de las opciones de tratamiento, as\u00ed como los riesgos y beneficios esperados.<\/p>\n\n<p>El paciente ha expresado su deseo de proceder con la cirug\u00eda y creemos que es una opci\u00f3n razonable.<\/p>\n\n<p>Educamos al paciente sobre los riesgos inherentes e inevitables que incluyen, pero no se limitan a: infecci\u00f3n, rigidez, da\u00f1o en nervios y vasos sangu\u00edneos, p\u00e9rdida de sangre que puede requerir transfusiones, co\u00e1gulos sangu\u00edneos, dolor persistente o agravado, aflojamiento o fallo de implantes, inestabilidad, hormigueo o entumecimiento, anestesia y complicaciones sist\u00e9micas incluyendo card\u00edacas, pulmonares, neurol\u00f3gicas e incluso la muerte.<\/p>\n\n<p>Tambi\u00e9n hablamos sobre la posibilidad de no poder volver a actividades o empleos anteriores, la necesidad de cirug\u00edas futuras y el s\u00edndrome de dolor regional complejo.<\/p>\n\n<p>Hablamos sobre las opciones de tratamiento y el paciente opt\u00f3 por el manejo quir\u00fargico. Hablamos sobre riesgos y beneficios, incluyendo infecci\u00f3n, hemorragia, lesiones en nervios y vasos adyacentes, rehabilitaci\u00f3n, rigidez de rodilla, necesidad de <a href=\"https:\/\/www.cortho.org\/es\/rodilla\/reemplazo-total-de-rodilla\/\">reemplazo de rodilla<\/a> en el futuro, complicaciones sist\u00e9micas como co\u00e1gulos sangu\u00edneos, complicaciones card\u00edacas, pulmonares y neurol\u00f3gicas, incluyendo la muerte.  El paciente lo entendi\u00f3 y firm\u00f3 un consentimiento informado.<\/p>\n\n<p>La paciente fue llevada al quir\u00f3fano, donde la colocaron sobre una mesa de quir\u00f3fano bien acolchada. Se indujo anestesia general. La extremidad inferior derecha se prepar\u00f3 y coloc\u00f3 de forma as\u00e9ptica de la manera habitual tras la aplicaci\u00f3n del torniquete en la parte baja del muslo. Se pidi\u00f3 tiempo muerto.   <\/p>\n\n<p>Se administr\u00f3 antibi\u00f3tico preoperatorio. El torniquete estaba elevado. El portal de entrada lateral se realiz\u00f3 mediante una incisi\u00f3n parapatelar. Se insert\u00f3 un artroscopio. Se realiz\u00f3 una incisi\u00f3n parapatelariana medial tras guiarla con una aguja espinal.    <\/p>\n\n<p>El examen del compartimento tibiofemoral medial mostr\u00f3 una compleja ruptura del cuerno posterior del menisco medial junto con osteoartritis de grado 2 a grado 3 del c\u00f3ndilo femoral medial.<\/p>\n\n<p>El desbridamiento del menisco se realiz\u00f3 mediante afeitadora y mordedores. La condroplastia por desbridamiento tambi\u00e9n se realizaba mediante el uso de una afeitadora. El examen de la muesca intercondilar mostr\u00f3 LCA intacto.<a href=\"https:\/\/www.cortho.org\/es\/knee\/ligamento-cruzado-anterior\/\"> El examen del compartimento tibiofemoral lateral mostr\u00f3 menisco y cart\u00edlago intactos.<\/a>   <\/p>\n\n<p>El examen del compartimento patelofemoral mostr\u00f3 una lesi\u00f3n osteocondral de grado 3 a grado 4 en la faceta lateral de la r\u00f3tula. Troclea estaba intacta. El desbridamiento de la r\u00f3tula se realizaba mediante una afeitadora.  <\/p>\n\n<p>Se insert\u00f3 un artroscopio a trav\u00e9s de la puerta medial, se insert\u00f3 la afeitadora en la porta lateral, y se realiz\u00f3 un mayor equilibrio del menisco medial, as\u00ed como condroplastia de la r\u00f3tula. Se tomaron y guardaron las fotos finales. La rodilla fue completamente irrigada y drenada.  <\/p>\n\n<p>El cierre se hizo usando nylon #3-0. El vendaje se aplic\u00f3 con 20 cc de marca\u00edna al 0,5% mezclada con 40 mg de Depo-Medrol inyectada en la rodilla. El ap\u00f3sito se hizo con Xeroform, 4 x 8, ABD, Webril y Ace wrap. El paciente se recuper\u00f3. El paciente fue extubado y trasladado a recuperaci\u00f3n en estado estable.    <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"575\" height=\"287\" data-src=\"\/wp-content\/uploads\/2023\/06\/Intraoperative-images-3.png\" alt=\"Im\u00e1genes intraoperatorias\" class=\"wp-image-30974 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 575px; --smush-placeholder-aspect-ratio: 575\/287;\" \/><\/figure>\n<\/div>\n<p class=\"has-text-align-center\"><strong>Im\u00e1genes intraoperatorias<\/strong><\/p>\n\n<p>Hoy est\u00e1 aqu\u00ed para su visita postoperatoria de una semana, no hicieron falta radiograf\u00edas. El dolor est\u00e1 bien controlado. Niega fiebre, escalofr\u00edos. Despu\u00e9s de que el m\u00e9dico discutiera las opciones de tratamiento, hemos decidido proceder con fisioterapia formal as\u00ed como con un programa de ejercicios en casa para la rehabilitaci\u00f3n de la rodilla.   <\/p>\n\n<p>Revisamos las im\u00e1genes artrosc\u00f3picas y quitamos los puntos durante la visita de hoy. Continuaremos con hielo y elevaci\u00f3n de la rodilla para reducir la hinchaz\u00f3n y el dolor. Seguiremos utilizando la movilizaci\u00f3n temprana y la profilaxis mec\u00e1nica para reducir las probabilidades de una trombosis venosa profunda.  <\/p>\n\n<p>Reduciremos poco a poco cualquier medicamento narc\u00f3tico y avanzaremos a antiinflamatorios y paracetamol, siempre que no haya contraindicaciones para estos medicamentos.<\/p>\n\n<p>Tambi\u00e9n hablamos sobre los riesgos, beneficios y efectos secundarios comunes de tomar estos medicamentos en la visita de hoy. Los ver\u00e9 de nuevo en tres semanas para evaluar su progreso. Nos llamar\u00e1n mientras tanto, si tienen alguna pregunta o preocupaci\u00f3n, antes de la visita de seguimiento.  <\/p>\n\n<p>El m\u00e9dico habl\u00f3 sobre opciones de tratamiento como fisioterapia, resonancia magn\u00e9tica, inyecci\u00f3n, cirug\u00eda, y acordamos optar por un manejo conservador por ahora. La fisioterapia se empezar\u00e1 como se ha discutido. Tras discutir las opciones de tratamiento y los riesgos de la inyecci\u00f3n, el paciente quiso proceder con la inyecci\u00f3n para reducir el dolor y la hinchaz\u00f3n.  <\/p>\n\n<p>Tras una preparaci\u00f3n est\u00e9ril, se inyectaron 7 cc de lidoca\u00edna al 1% y 80 mg de depo-medrol en la rodilla derecha. El paciente toler\u00f3 bien el procedimiento y no hubo complicaciones. Se discutieron en detalle el dolor post-inyecci\u00f3n, el aumento de la glucosa en sangre, la decoloraci\u00f3n de la piel, la atrofia grasa y los signos de infecci\u00f3n.  <\/p>\n\n<p>Despu\u00e9s de un par de veces que el paciente fue atendido en la consulta, acordamos optar por un manejo conservador y fisioterapia. El paciente se somete a una revisi\u00f3n peri\u00f3dica cada cuatro semanas para evaluar el progreso. <\/p>\n\n<p><em>Aviso legal \u2013 El nombre, edad, sexo, fechas y eventos del paciente han sido modificados o modificados para proteger su privacidad.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una rotura lateral del menisco afecta al cart\u00edlago semicircular que recubre el exterior de la articulaci\u00f3n de la rodilla. A trav\u00e9s de torsi\u00f3n o una lesi\u00f3n traum\u00e1tica, la prueba de McMurray es uno de los ex\u00e1menes principales para lesiones de menisco. Tu rodilla ser\u00e1 flexionada por tu m\u00e9dico antes de enderezarla y rotarla. Esto pone [&hellip;]<\/p>\n","protected":false},"featured_media":69786,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Cirug\u00eda de rodilla: menisco medial femenino | Ortopedia Completa","_seopress_titles_desc":"Otro estudio de caso trata sobre la cirug\u00eda de rodilla: menisco medial en una mujer de 68 a\u00f1os de Complete Orthopedics con m\u00faltiples ubicaciones en Nueva York.","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"case-study-categories":[176],"case-study-tags":[],"class_list":["post-69785","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case-study-categories-estudios-de-casos-de-medicina-deportiva"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-studies\/69785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/media\/69786"}],"wp:attachment":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/media?parent=69785"}],"wp:term":[{"taxonomy":"case-study-categories","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-study-categories?post=69785"},{"taxonomy":"case-study-tags","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-study-tags?post=69785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}