{"id":69686,"date":"2025-10-24T04:22:02","date_gmt":"2025-10-24T04:22:02","guid":{"rendered":"https:\/\/cortho.org\/case-studies\/estudio-de-caso-manejo-de-una-mujer-de-55-anos-con-desgarro-del-cuadriceps-de-rodilla-izquierda-desgarro-del-menisco-lateral-y-desgarro-parcial-del-ligamento-cruzado-anterior\/"},"modified":"2026-01-03T03:42:59","modified_gmt":"2026-01-03T03:42:59","slug":"estudio-de-caso-manejo-de-una-mujer-de-55-anos-con-desgarro-del-cuadriceps-de-rodilla-izquierda-desgarro-del-menisco-lateral-y-desgarro-parcial-del-ligamento-cruzado-anterior","status":"publish","type":"case-studies","link":"https:\/\/www.cortho.org\/es\/estudios-de-caso\/medicina-deportiva\/estudio-de-caso-manejo-de-una-mujer-de-55-anos-con-desgarro-del-cuadriceps-de-rodilla-izquierda-desgarro-del-menisco-lateral-y-desgarro-parcial-del-ligamento-cruzado-anterior\/","title":{"rendered":"Estudio de caso: Manejo de una mujer de 55 a\u00f1os con desgarro del cu\u00e1driceps de rodilla izquierda, desgarro del menisco lateral y desgarro parcial del ligamento cruzado anterior"},"content":{"rendered":"\n<p>El paciente est\u00e1 en nuestra consulta, con <a href=\"\/faq\/knee\/knee-pain\/\">quejas de dolor en la rodilla izquierda y p\u00e9rdida de funci\u00f3n<\/a> desde hace un mes. La paciente sufri\u00f3 una lesi\u00f3n en una ca\u00edda, y la paciente afirma que no puede ejercer presi\u00f3n sobre la rodilla. La paciente tambi\u00e9n afirma que nota un espacio entre la r\u00f3tula. La paciente trabaja como guardia de seguridad en una cl\u00ednica y sufri\u00f3 la lesi\u00f3n cuando intentaba sujetar a un paciente y se cay\u00f3.   <\/p>\n\n<p>El dolor es extremadamente intenso (10\/10). El dolor es constante. El problema no ha cambiado desde que empez\u00f3. El hielo y el ibuprofeno mejoran los s\u00edntomas. Actualmente est\u00e1 tomando relajantes musculares y AINEs para el dolor. No puede caminar sin ayuda y utiliza un bast\u00f3n para caminar.     <\/p>\n\n<p>El paciente tiene antecedentes m\u00e9dicos significativos para diabetes y psoriasis, ambos bien controlados con medicaci\u00f3n. Neg\u00f3 cualquier historial quir\u00fargico previo. El paciente es al\u00e9rgico a los mariscos. No fuma y consume alcohol socialmente.   <\/p>\n\n<p>En el examen f\u00edsico, el paciente estaba calmado, consciente, cooperativo y bien orientado hacia el tiempo, el lugar y la persona. Al examinar la rodilla izquierda, hubo hinchaz\u00f3n moderada. El paciente no pudo realizar una elevaci\u00f3n activa de pierna recta. Se sinti\u00f3 un vac\u00edo sobre el polo proximal de la r\u00f3tula. El rango de movimiento se limit\u00f3 a causa del dolor. No hab\u00eda d\u00e9ficit neurovascular distal.     <\/p>\n\n<p>El examen de la rodilla contralateral no fue nada destacable.<\/p>\n\n<p>La radiograf\u00eda de la rodilla izquierda indic\u00f3 hinchaz\u00f3n de tejidos blandos por delante de la r\u00f3tula y la inclinaci\u00f3n de la r\u00f3tula.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img decoding=\"async\" width=\"1384\" height=\"1999\" data-src=\"\/wp-content\/uploads\/2020\/06\/LeftKneeQuadricepsTear.jpg\" alt=\"Radiograf\u00eda de la rodilla izquierda en vista lateral\" class=\"wp-image-9653 lazyload\" style=\"--smush-placeholder-width: 1384px; --smush-placeholder-aspect-ratio: 1384\/1999;width:506px;height:auto\" title=\"Radiograf\u00eda de la rodilla izquierda en vista lateral\" data-srcset=\"https:\/\/www.cortho.org\/wp-content\/uploads\/2020\/06\/LeftKneeQuadricepsTear.jpg 1384w, https:\/\/www.cortho.org\/wp-content\/uploads\/2020\/06\/LeftKneeQuadricepsTear-768x1109.jpg 768w, https:\/\/www.cortho.org\/wp-content\/uploads\/2020\/06\/LeftKneeQuadricepsTear-1063x1536.jpg 1063w\" data-sizes=\"(max-width: 1384px) 100vw, 1384px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n<\/div>\n<p class=\"has-text-align-center\"><strong>Radiograf\u00eda de la rodilla izquierda en vista lateral.<\/strong><\/p>\n\n<p>La resonancia sugiri\u00f3 una ruptura completa del tend\u00f3n del cu\u00e1driceps en la inserci\u00f3n rotuliana. El derrame articular se comunica a trav\u00e9s del defecto tendinoso con una recogida de l\u00edquido prepatelar. Desgarro intrasustancial de bajo<a href=\"https:\/\/www.cortho.org\/es\/knee\/ligamento-cruzado-anterior\/\"> grado en el origen del LCA<\/a>. <a href=\"\/faq\/knee\/meniscal-tear-of-the-knee\/\">Desgarro radial en el borde libre del cuerpo meniscal lateral.<\/a>   <\/p>\n\n<p><\/p>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"316\" height=\"315\" data-src=\"\/wp-content\/uploads\/2020\/06\/LeftKneeQuadricepsTear2.jpg\" alt=\"Resonancia magn\u00e9tica de la rodilla izquierda en la vista sagital y coronal\" class=\"wp-image-9652 lazyload\" title=\"Resonancia magn\u00e9tica de la rodilla izquierda en la vista sagital y coronal\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 316px; --smush-placeholder-aspect-ratio: 316\/315;\" \/><\/figure>\n<\/div><div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"330\" height=\"306\" data-src=\"\/wp-content\/uploads\/2020\/06\/LeftKneeQuadricepsTear3.jpg\" alt=\"Resonancia magn\u00e9tica de la rodilla izquierda en la vista sagital y coronal 2\" class=\"wp-image-9651 lazyload\" title=\"Resonancia magn\u00e9tica de la rodilla izquierda en la vista sagital y coronal 2\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 330px; --smush-placeholder-aspect-ratio: 330\/306;\" \/><\/figure>\n<\/div>\n<p class=\"has-text-align-center\"><strong>Resonancia magn\u00e9tica de la rodilla izquierda en la vista sagital y coronal.<\/strong><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"343\" height=\"308\" data-src=\"\/wp-content\/uploads\/2020\/06\/LeftKneeQuadricepsTear4.jpg\" alt=\"Resonancia magn\u00e9tica de la rodilla izquierda en la secci\u00f3n sagital\" class=\"wp-image-9650 lazyload\" title=\"Resonancia magn\u00e9tica de la rodilla izquierda en la secci\u00f3n sagital  \" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 343px; --smush-placeholder-aspect-ratio: 343\/308;\" \/><\/figure>\n<\/div>\n<p class=\"has-text-align-center\"><strong>Resonancia magn\u00e9tica de la rodilla izquierda en la secci\u00f3n sagital.<\/strong><\/p>\n\n<p>Todas las opciones de tratamiento, tanto quir\u00fargicas como no quir\u00fargicas, se discutieron extensamente con el paciente. Tambi\u00e9n se discutieron con el paciente riesgos, beneficios y alternativas. El paciente acept\u00f3 seguir adelante con la intervenci\u00f3n quir\u00fargica.  <\/p>\n\n<h2 class=\"wp-block-heading\">DIAGN\u00d3STICOS PREOPERATORIOS:<\/h2>\n\n<ol class=\"wp-block-list\">\n<li>Desgarro del cu\u00e1driceps de la rodilla izquierda.<\/li>\n\n\n\n<li>Desgarro del menisco lateral de la rodilla izquierda.<\/li>\n\n\n\n<li>Desgarro parcial del ligamento cruzado anterior de la rodilla izquierda.<\/li>\n<\/ol>\n\n<h2 class=\"wp-block-heading\">DIAGN\u00d3STICOS POSTOPERATORIOS:<\/h2>\n\n<ol class=\"wp-block-list\">\n<li>Desgarro del cu\u00e1driceps de la rodilla izquierda.<\/li>\n\n\n\n<li>Desgarro del menisco lateral de la rodilla izquierda.<\/li>\n\n\n\n<li>Desgarro parcial del ligamento cruzado anterior de la rodilla izquierda.<\/li>\n\n\n\n<li>Troclea de da\u00f1o condral de grado 2 a 3.<\/li>\n<\/ol>\n\n<h2 class=\"wp-block-heading\">OPERACI\u00d3N:<\/h2>\n\n<ol class=\"wp-block-list\">\n<li>Artroscopia de rodilla con meniscectom\u00eda lateral parcial.<\/li>\n\n\n\n<li>Condroplastia artrosc\u00f3pica de la r\u00f3tula.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.cortho.org\/es\/knee\/ligamento-cruzado-anterior\/\">Desbridamiento del LCA<\/a>, rodilla izquierda.<\/li>\n\n\n\n<li>Reparaci\u00f3n abierta de los cu\u00e1driceps, rodilla izquierda.<\/li>\n<\/ol>\n\n<p><strong>PROCEDIMIENTO:<\/strong> El paciente fue llevado al quir\u00f3fano, donde lo colocaron sobre una mesa de operaciones bien acolchada. Se indujo anestesia general. El extremo inferior izquierdo fue colocado en un torniquete alto. La rodilla izquierda estaba preparada as\u00e9pticamente y colocada de la manera habitual. Se pidi\u00f3 un tiempo muerto. Se aplic\u00f3 un torniquete e infl\u00f3. El tiempo del torniquete fue de 103 minutos.      <\/p>\n\n<p>Se cre\u00f3 un portal de entrada lateral izquierdo y se accedi\u00f3 al telescopio. La rodilla fue lavada con mucho l\u00edquido para limpiar la sangre. La visualizaci\u00f3n no era adecuada para la sangre.  <\/p>\n\n<p>El endoscopio se traslad\u00f3 al compartimento tibiofemoral medial. El menisco medial estaba intacto. No hubo da\u00f1o condral. El endoscopio se traslad\u00f3 a la zona intercondilar donde se encontr\u00f3 una ruptura parcial del LCA en el lado lateral. El desbridamiento ya estaba hecho. El resto del 90% del LCA estaba intacto.     <\/p>\n\n<p>El endoscopio se traslad\u00f3 al compartimento tibiofemoral lateral, donde estaba presente la rotura del borde medial del menisco lateral. El desgarro se limpiaba usando mordedores y afeitadoras de lado derecho. El resto del menisco lateral permaneci\u00f3 intacto. No hubo da\u00f1o condral.   <\/p>\n\n<p>El endoscopio se traslad\u00f3 a la articulaci\u00f3n patelofemoral donde se encontr\u00f3 da\u00f1o condral de troclea grado 2 a grado 3. El da\u00f1o condral fue desbridado desde la puerta medial y seguido por la puerta lateral. Se realiz\u00f3 un lavado abundante. Se tomaron y guardaron fotos artrosc\u00f3picas.   <\/p>\n\n<p>Se retir\u00f3 el telescopio. La rodilla estaba extendida. Se extendi\u00f3 la mesa y se realiz\u00f3 un drapeado adecuado. Se realiz\u00f3 una incisi\u00f3n vertical en la l\u00ednea media que se centr\u00f3 sobre el polo superior de la r\u00f3tula.   <\/p>\n\n<p>Se encontr\u00f3 que el tend\u00f3n del cu\u00e1driceps estaba completamente roto. El tend\u00f3n estaba desbridado. El mu\u00f1\u00f3n del tend\u00f3n estaba sobre la r\u00f3tula fue extra\u00eddo. El hueso estaba decorticado a los m\u00e1rgenes sangrantes frescos. Se construyeron tres t\u00faneles trans\u00f3seos y se colocaron lazos de seda para su uso futuro.    <\/p>\n\n<p>Ahora, el tend\u00f3n se sutur\u00f3 usando #5 FiberWire con puntada Krackow x2. Las cuatro colas del #5 FiberWire pasaron a trav\u00e9s de los tres t\u00faneles hasta la r\u00f3tula. Los FiberWires lateral y medial se ataron entre s\u00ed y los nudos quedaron enterrados.  <\/p>\n\n<p>El retin\u00e1culo lateral y el medial se repararon usando el #2 FiberWire. Tras un cierre adecuado, la herida volvi\u00f3 a ser lavada. El cierre de la piel se realiz\u00f3 usando Vicryl #2-0 y Monocryl #4-0.  <\/p>\n\n<p>Los portales artrosc\u00f3picos se cerraron usando nylon #4-0. El vendaje se realiz\u00f3 con Steri-Strips, Adaptic, 4 x 4, ABD, Webril y Ace wrap. Se retir\u00f3 el torniquete. El paciente fue extubado y trasladado a la unidad de recuperaci\u00f3n en estado estable.   <\/p>\n\n<p><em>Aviso legal \u2013 El nombre, edad, sexo, fechas y eventos del paciente han sido modificados o modificados para proteger su privacidad.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El paciente est\u00e1 en nuestra consulta, con quejas de dolor en la rodilla izquierda y p\u00e9rdida de funci\u00f3n desde hace un mes. La paciente sufri\u00f3 una lesi\u00f3n en una ca\u00edda, y la paciente afirma que no puede ejercer presi\u00f3n sobre la rodilla. La paciente tambi\u00e9n afirma que nota un espacio entre la r\u00f3tula. La paciente [&hellip;]<\/p>\n","protected":false},"featured_media":69687,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Estudio de caso: Manejo de desgarros de rodilla izquierda en una mujer de 55 a\u00f1os ","_seopress_titles_desc":"Este estudio de caso trata sobre desgarro de cu\u00e1driceps de rodilla EFT, desgarro de menisco lateral y desgarro parcial del LCA de Complete Orthopedics, con m\u00faltiples ubicaciones en Nueva York.","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"case-study-categories":[177],"case-study-tags":[],"class_list":["post-69686","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case-study-categories-medicina-deportiva"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-studies\/69686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/media\/69687"}],"wp:attachment":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/media?parent=69686"}],"wp:term":[{"taxonomy":"case-study-categories","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-study-categories?post=69686"},{"taxonomy":"case-study-tags","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-study-tags?post=69686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}