{"id":69648,"date":"2025-10-20T09:51:52","date_gmt":"2025-10-20T09:51:52","guid":{"rendered":"https:\/\/cortho.org\/case-studies\/estudio-de-caso-manejo-de-la-capsulitis-adhesiva-del-hombro-izquierdo-en-un-hombre-de-55-anos\/"},"modified":"2026-01-03T03:40:22","modified_gmt":"2026-01-03T03:40:22","slug":"estudio-de-caso-manejo-de-la-capsulitis-adhesiva-del-hombro-izquierdo-en-un-hombre-de-55-anos","status":"publish","type":"case-studies","link":"https:\/\/www.cortho.org\/es\/estudios-de-caso\/estudio-de-caso-manejo-de-la-capsulitis-adhesiva-del-hombro-izquierdo-en-un-hombre-de-55-anos\/","title":{"rendered":"Estudio de caso: Manejo de la capsulitis adhesiva del hombro izquierdo en un hombre de 55 a\u00f1os"},"content":{"rendered":"\n<p>El paciente es un hombre de 55 a\u00f1os que est\u00e1 siendo atendido hoy con <a href=\"\/faq\/shoulder\/shoulder-pain\/\" target=\"_blank\" rel=\"noreferrer noopener\">quejas de dolor en el hombro izquierdo<\/a> debido a un accidente de tr\u00e1fico ocurrido hace un a\u00f1o. El a\u00f1o pasado le hicieron una artroscopia en el hombro izquierdo con un m\u00e9dico externo. Se realizaron <a href=\"https:\/\/www.cortho.org\/es\/hombro\/\" target=\"_blank\" rel=\"noreferrer noopener\">acromioplastias y desbridamiento subacromial<\/a> . Tras la cirug\u00eda, el paciente empez\u00f3 a desarrollar capsulitis adhesiva, que se trataba de forma conservadora con fisioterapia.  <\/p>\n\n<p>El dolor en el hombro est\u00e1 asociado a la restricci\u00f3n de movimiento y es agudo en ocasiones. Se agrava con movimientos bruscos. El paciente es zurdo y le resulta extremadamente dif\u00edcil realizar actividades diarias como peinarse, levantar cosas, conducir, jugar con sus nietos y mantener su higiene personal.  <\/p>\n\n<p>El paciente se estaba recuperando bien con terapia. Recientemente, el paciente se someti\u00f3 a una cirug\u00eda abdominal tras la cual los movimientos del hombro izquierdo se deterioraron. El paciente trabaja como recepcionista m\u00e9dico en una consulta m\u00e9dica.  <\/p>\n\n<p>El paciente no fuma y bebe socialmente. Niega cualquier alergia conocida a los medicamentos. Su historial m\u00e9dico inclu\u00eda hipertensi\u00f3n, asma e hiperlipidemia. Todas sus condiciones m\u00e9dicas est\u00e1n controladas con medicaci\u00f3n.   <\/p>\n\n<p>En el examen, el paciente est\u00e1 tranquilo, consciente, cooperativo y bien orientado hacia el tiempo, el lugar y la persona. Al examinar el hombro izquierdo, el paciente se sienta con la esc\u00e1pula extendida y deprimida. Hay sensibilidad en la palpaci\u00f3n sobre el trapecio y los romboides, as\u00ed como en la parte anterior del supraespinoso y b\u00edceps.  <\/p>\n\n<p>No hay sensibilidad en la palpaci\u00f3n sobre el cuello, clav\u00edcula, esc\u00e1pula y codo. No hay hinchaz\u00f3n de tejidos blandos ni equimosis. El paciente tiene un rango de movimiento limitado del hombro en todos los planos secundario a la molestia (abducci\u00f3n 40, rotaci\u00f3n externa 30, rotaci\u00f3n interna hasta SI).  <\/p>\n\n<p>El paciente no puede tolerar las pruebas de estabilidad. Fuerza en los m\u00fasculos del manguito rotador en 4+\/5 y asociada al dolor. La prueba de Hawkins es positiva, la de Neer es negativa. El neurovascular distal est\u00e1 intacto.   <\/p>\n\n<p>Al examinar la extremidad contralateral, el paciente no es sensible a la palpaci\u00f3n y tiene un excelente rango de movimiento, estabilidad y fuerza.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" data-src=\"https:\/\/www.cortho.org\/wp-content\/smush-webp\/2020\/06\/ManagementofAdhesive.jpg.webp\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/762;\" \/><\/figure>\n<\/div>\n<p class=\"has-text-align-center\" id=\"caption-attachment-9520\"><strong>Radiograf\u00eda del hombro en vista AP<\/strong><\/p>\n\n<p>La resonancia magn\u00e9tica del hombro izquierdo sugiri\u00f3 tendinosis del tend\u00f3n supraespinoso con una ruptura parcial de la superficie articular de las fibras anteriores y medias del tend\u00f3n. Tendinosis del tend\u00f3n infraespinoso. <a href=\"https:\/\/www.cortho.org\/general\/management-radiculopathy-covid-19\/\" target=\"_blank\" rel=\"noreferrer noopener\">L\u00edquido bursal subacromial\/subdeltoideo que refleja bursitis<\/a>. Degeneraci\u00f3n y desgarro del labrum anterosuperior.  <\/p>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" data-src=\"https:\/\/www.cortho.org\/wp-content\/smush-webp\/2020\/06\/ManagementofAdhesive2.jpg.webp\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 499px; --smush-placeholder-aspect-ratio: 499\/499;\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/www.cortho.org\/wp-content\/smush-webp\/2020\/06\/ManagementofAdhesive3.jpg.webp\" alt=\"\" style=\"--smush-placeholder-width: 499px; --smush-placeholder-aspect-ratio: 499\/536;width:384px;height:auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/figure>\n<\/div><\/div>\n<\/div>\n\n<p class=\"has-text-align-center\"><strong>Imagen por resonancia magn\u00e9tica del hombro en secciones axial y coronal<\/strong><\/p>\n\n<p>Discutimos las opciones de tratamiento y el paciente opt\u00f3 por un manejo quir\u00fargico en forma de manipulaci\u00f3n bajo anestesia. Hablamos sobre los riesgos y complicaciones de la cirug\u00eda, incluyendo fracturas, reca\u00edda de la capsulitis adhesiva, incapacidad para recuperar el rango completo de movimiento, necesidad de liberaci\u00f3n capsular artrosc\u00f3pica, inflamaci\u00f3n, dolor, rehabilitaci\u00f3n, entre otros. El paciente comprend\u00eda los riesgos, beneficios y complicaciones, y firmaba su consentimiento informado.  <\/p>\n\n<p><strong>DIAGN\u00d3STICO PREOPERATORIO:<\/strong> Capsulitis adhesiva del hombro izquierdo.<\/p>\n\n<p><strong>DIAGN\u00d3STICO POSTOPERATORIO:<\/strong> Capsulitis adhesiva del hombro izquierdo.<\/p>\n\n<p><strong>OPERACI\u00d3N:<\/strong> Manipulaci\u00f3n bajo anestesia seguida de inyecci\u00f3n de cortisona en la articulaci\u00f3n glenohumeral izquierda.<\/p>\n\n<p><strong>DESCRIPCI\u00d3N DEL PROCEDIMIENTO:<\/strong> La paciente fue llevada al quir\u00f3fano, donde ella misma fue mantenida en la camilla de transporte. El anestesista le administr\u00f3 un bloqueo braquial antes de entrar en la sala. <\/p>\n\n<p>Se realizaba sedaci\u00f3n consciente y, una vez completamente sedado, el hombro izquierdo se manipulaba bajo anestesia. Se notar\u00eda el crepitus de la ruptura de las adherencias durante la abducci\u00f3n y la rotaci\u00f3n interna. Se logr\u00f3 un rango completo de movimiento bajo anestesia.  <\/p>\n\n<p>A continuaci\u00f3n, se inyectaron 80 mg de Depo-Medrol mezclados con 3 cc de Marca\u00edna al 0,5% y 3 cc de lidoca\u00edna al 1% en la articulaci\u00f3n glenohumeral izquierda. El paciente fue trasladado a la unidad de estancia postoperatoria en estado estable. <\/p>\n\n<p><em>Aviso legal \u2013 El nombre, edad, sexo, fechas y eventos del paciente han sido modificados o modificados para proteger su privacidad.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El paciente es un hombre de 55 a\u00f1os que est\u00e1 siendo atendido hoy con quejas de dolor en el hombro izquierdo debido a un accidente de tr\u00e1fico ocurrido hace un a\u00f1o. El a\u00f1o pasado le hicieron una artroscopia en el hombro izquierdo con un m\u00e9dico externo. Se realizaron acromioplastias y desbridamiento subacromial . Tras la [&hellip;]<\/p>\n","protected":false},"featured_media":69649,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Estudio de caso: Manejo del hombro izquierdo en un hombre de 55 a\u00f1os ","_seopress_titles_desc":"Un estudio de caso de un paciente masculino con capsulitis adesiva del hombro izquierdo de los m\u00e9dicos de Complete Orthopedics con m\u00faltiples ubicaciones en Nueva York.","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"case-study-categories":[177],"case-study-tags":[],"class_list":["post-69648","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case-study-categories-medicina-deportiva"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-studies\/69648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/media\/69649"}],"wp:attachment":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/media?parent=69648"}],"wp:term":[{"taxonomy":"case-study-categories","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-study-categories?post=69648"},{"taxonomy":"case-study-tags","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-study-tags?post=69648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}