{"id":69628,"date":"2025-10-19T05:19:39","date_gmt":"2025-10-19T05:19:39","guid":{"rendered":"https:\/\/cortho.org\/case-studies\/estudio-de-caso-manejo-de-la-ruptura-del-tendon-de-aquiles-en-un-jugador-de-baloncesto-de-35-anos\/"},"modified":"2026-01-03T03:38:42","modified_gmt":"2026-01-03T03:38:42","slug":"estudio-de-caso-manejo-de-la-ruptura-del-tendon-de-aquiles-en-un-jugador-de-baloncesto-de-35-anos","status":"publish","type":"case-studies","link":"https:\/\/www.cortho.org\/es\/estudios-de-caso\/estudios-de-casos-de-medicina-deportiva\/estudio-de-caso-manejo-de-la-ruptura-del-tendon-de-aquiles-en-un-jugador-de-baloncesto-de-35-anos\/","title":{"rendered":"Estudio de caso: Manejo de la ruptura del tend\u00f3n de Aquiles en un jugador de baloncesto de 35 a\u00f1os"},"content":{"rendered":"\n<p>Una jugadora de baloncesto de 35 a\u00f1os se present\u00f3 un d\u00eda despu\u00e9s de sufrir una lesi\u00f3n en el tobillo derecho mientras jugaba. La paciente informa que escuch\u00f3 un chasquido mientras saltaba durante el partido. Inmediatamente sinti\u00f3 dolor e hinchaz\u00f3n en el tobillo derecho con dificultad para caminar.  <\/p>\n\n<p>Los pacientes aplicaron hielo en el tobillo derecho y usaron analg\u00e9sicos en forma de ibuprofeno. El paciente niega cualquier uso de cualquier medicamento actual. El paciente no fuma y niega cualquier uso de drogas il\u00edcitas. El paciente niega cualquier alergia conocida a los medicamentos.   <\/p>\n\n<p>En el examen f\u00edsico del tobillo derecho, se observ\u00f3 un espacio palpable a 5 cm por encima de la inserci\u00f3n calc\u00e2nea del tend\u00f3n de Aquiles. La dorsiflexi\u00f3n del tobillo derecho era normal, aunque la flexi\u00f3n plantar estaba ausente. La prueba de Thompson, la prueba de presi\u00f3n y la prueba de Matles dieron positivo.  <\/p>\n\n<p>Una resonancia magn\u00e9tica del tobillo derecho mostr\u00f3 una <a href=\"\/?s=Achilles+Tendon+Injuries\">ruptura completa del tend\u00f3n de Aquiles derecho<\/a>. La ruptura fue a trav\u00e9s de la zona de la divisoria hidrogr\u00e1fica. Se le recomend\u00f3 a la paciente la reparaci\u00f3n quir\u00fargica del tend\u00f3n desgarrado. Los riesgos, beneficios y complicaciones de la cirug\u00eda se explicaron en detalle al paciente. El paciente verbaliz\u00f3 su acuerdo y firm\u00f3 el consentimiento informado.    <\/p>\n\n<p><\/p>\n\n<p class=\"has-text-align-center\"><img decoding=\"async\" width=\"450\" height=\"600\" data-src=\"\/wp-content\/uploads\/2021\/04\/Management-of-Tendoachilles-Rupture.jpg\" alt=\"Imagen intraoperatoria de la reparaci\u00f3n del tendoaquiles.\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 450px; --smush-placeholder-aspect-ratio: 450\/600;\" \/><\/p>\n\n<p class=\"has-text-align-center\" id=\"caption-attachment-12487\"><strong>Imagen intraoperatoria de la reparaci\u00f3n del tendoaquiles.<\/strong><\/p>\n\n<p><strong>DIAGN\u00d3STICO PREOPERATORIO:<\/strong> Tend\u00f3n tend\u00f3n de Aquiles en el lado derecho.<\/p>\n\n<p><strong>DIAGN\u00d3STICO POSTOPERATORIO:<\/strong> Tend\u00f3n tend\u00f3n de Aquiles en el lado derecho.<\/p>\n\n<p><strong>OPERACI\u00d3N:<\/strong> Reparaci\u00f3n del tend\u00f3n de Aquiles abierto.<\/p>\n\n<p><strong>DESCRIPCI\u00d3N DEL PROCEDIMIENTO:<\/strong> El paciente fue trasladado al quir\u00f3fano, donde se le indujo anestesia general. El paciente fue intubado y puesto boca abajo en una posici\u00f3n bien acolchada. Todas las prominencias \u00f3seas estaban bien acolchadas. La extremidad inferior derecha estaba preparada y colocada as\u00e9pticamente de la manera habitual. Se aplic\u00f3 un torniquete en el muslo. Se administr\u00f3 el antibi\u00f3tico preoperatorio. El torniquete estaba inflado. Se pidi\u00f3 un tiempo muerto.       <\/p>\n\n<p><\/p>\n\n<p class=\"has-text-align-center\"><img decoding=\"async\" width=\"450\" height=\"600\" data-src=\"\/wp-content\/uploads\/2021\/04\/Management-of-Tendoachilles-Rupture-2.jpg\" alt=\"Imagen intraoperatoria que muestra la reparaci\u00f3n del tend\u00f3n de Aquiles.\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 450px; --smush-placeholder-aspect-ratio: 450\/600;\" \/><\/p>\n\n<p class=\"has-text-align-center\" id=\"caption-attachment-12488\"><strong>Imagen intraoperatoria que muestra la reparaci\u00f3n del tend\u00f3n de Aquiles.<\/strong><\/p>\n\n<p>Se realiz\u00f3 una incisi\u00f3n medial a la l\u00ednea media, que est\u00e1 dos tercios por encima y un tercio por debajo del espacio en el tend\u00f3n de Aquiles. Con una disecci\u00f3n aguda, se alcanzaba el paraten\u00f3n y se incisionaba a lo largo de la l\u00ednea de la incisi\u00f3n. Se ver\u00eda una rotura completa del tend\u00f3n de Aquiles. Se planificaron suturas modificadas proximales tipo Krackow y se utilizaron dos SutureTapes para realizar la sutura modificada con el lugar elegido previamente.   <\/p>\n\n<p>Las cuatro colas se pod\u00edan recuperar en el extremo inferior del toc\u00f3n. El mu\u00f1\u00f3n distal fue limpiado. Se realizaron dos incisiones distales sobre el calcano a ambos lados de la inserci\u00f3n del tend\u00f3n de Aquiles. El recuperador de sutura de pl\u00e1tano se pas\u00f3 por la incisi\u00f3n a lo largo del tend\u00f3n de Aquiles a ambos lados proximalmente y se extrajeron los dos FiberWires a cada lado.   <\/p>\n\n<p>Se planific\u00f3 el SwiveLock de 4,75 mm con un taladro en \u00e1ngulos de 45 y 45 grados lateralmente a la inserci\u00f3n del tend\u00f3n de Aquiles y en el calcaneo a ambos lados, seguido de la tapeada e inserci\u00f3n del SwiveLock.<\/p>\n\n<p>Las suturas se tensaron con el pie en flexi\u00f3n plantar a ambos lados y se apret\u00f3 el SwiveLock. Se pod\u00eda ver una buena reparaci\u00f3n. La reparaci\u00f3n se complement\u00f3 con el alambre de fibra #3-0 en el palo. El paratenon fue cerrado durante la reparaci\u00f3n. El cierre se realiz\u00f3 usando #0 Vicryl, #2-0 Vicryl y Monocryl.    <\/p>\n\n<p>Las incisiones SwiveLock se cerraron usando Vicryl #0 y nylon #4-0. La herida fue lavada antes de cerrarla. El vendaje se realiz\u00f3 usando 4&#215;8, ABD, Webril, f\u00e9rula posterior en flexi\u00f3n plantar. El paciente fue colocado en la cama, extubado y trasladado a la recuperaci\u00f3n en estado estable. Se aplic\u00f3 un yeso por encima de la rodilla en flexi\u00f3n plantar.    <\/p>\n\n<p>El yeso se cort\u00f3 en 2 semanas y se aplic\u00f3 un yeso por debajo de la rodilla en flexi\u00f3n plantar por gravedad. A las 3 semanas se retir\u00f3 el yeso y se le puso un yeso para caminar con cu\u00f1as en el tal\u00f3n, que se retiraron secuencialmente. <\/p>\n\n<p>Se permiti\u00f3 apoyar parcialmente el peso y se comenzaron ejercicios suaves y progresivos de rango activo de movimiento. El paciente apoyaba todo el peso y ten\u00eda buen rango de movimiento a las 8 semanas tras la cirug\u00eda. <\/p>\n\n<p><em>Aviso legal \u2013 El nombre, edad, sexo, fechas y eventos del paciente han sido modificados o modificados para proteger su privacidad.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una jugadora de baloncesto de 35 a\u00f1os se present\u00f3 un d\u00eda despu\u00e9s de sufrir una lesi\u00f3n en el tobillo derecho mientras jugaba. La paciente informa que escuch\u00f3 un chasquido mientras saltaba durante el partido. Inmediatamente sinti\u00f3 dolor e hinchaz\u00f3n en el tobillo derecho con dificultad para caminar. Los pacientes aplicaron hielo en el tobillo derecho [&hellip;]<\/p>\n","protected":false},"featured_media":69629,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Estudio de caso: Manejo de ruptura en un jugador de baloncesto de 35 a\u00f1os","_seopress_titles_desc":"Preparaci\u00f3n para pruebas isocin\u00e9ticas de dorsiflexi\u00f3n y flexi\u00f3n plantar utilizadas tras el tratamiento de rotura del tend\u00f3n de Aquiles. Los jugadores profesionales de baloncesto corren un alto riesgo de sufrirlo. ","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"case-study-categories":[176],"case-study-tags":[],"class_list":["post-69628","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case-study-categories-estudios-de-casos-de-medicina-deportiva"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-studies\/69628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/media\/69629"}],"wp:attachment":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/media?parent=69628"}],"wp:term":[{"taxonomy":"case-study-categories","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-study-categories?post=69628"},{"taxonomy":"case-study-tags","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-study-tags?post=69628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}