{"id":69511,"date":"2025-10-19T11:04:51","date_gmt":"2025-10-19T11:04:51","guid":{"rendered":"https:\/\/cortho.org\/case-studies\/estudio-de-caso-artroscopia-de-rodilla-derecha-reparacion-de-la-raiz-del-menisco-medial-y-condroplastia-en-un-paciente-de-59-anos\/"},"modified":"2026-01-02T16:42:07","modified_gmt":"2026-01-02T16:42:07","slug":"estudio-de-caso-artroscopia-de-rodilla-derecha-reparacion-de-la-raiz-del-menisco-medial-y-condroplastia-en-un-paciente-de-59-anos","status":"publish","type":"case-studies","link":"https:\/\/www.cortho.org\/es\/estudios-de-caso\/estudio-de-caso-artroscopia-de-rodilla-derecha-reparacion-de-la-raiz-del-menisco-medial-y-condroplastia-en-un-paciente-de-59-anos\/","title":{"rendered":"Estudio de caso: Artroscopia de rodilla derecha: Reparaci\u00f3n de la ra\u00edz del menisco medial y condroplastia en un paciente de 59 a\u00f1os"},"content":{"rendered":"\n<p>Una ra\u00edz de menisco que ha sido arrancada puede repararse quir\u00fargicamente. La reparaci\u00f3n meniscal puede realizarse de forma m\u00ednimamente invasiva usando un artroscopio que se introduce en la rodilla a trav\u00e9s de una peque\u00f1a incisi\u00f3n en forma de cerradura para localizar y reparar el menisco lesionado, o puede hacerse abiertamente bajo visi\u00f3n directa. <\/p>\n\n<p>El dolor e hinchaz\u00f3n en la rodilla son dos indicadores evidentes de una lesi\u00f3n de rodilla. Adem\u00e1s, podr\u00edas sentir dolor al mover la articulaci\u00f3n. Al doblar y estirar la pierna, puede sentirse tensa, bloqueada o como si se estuviera enganchando. Obviamente es motivo de preocupaci\u00f3n si oyes que la rodilla cruje y luego falla en el momento del contacto.   <\/p>\n\n<p>Un paciente de 59 a\u00f1os visit\u00f3 nuestra consulta con quejas sobre <a href=\"\/knee\/knee-pain\/\">dolor en la parte interna de la rodilla<\/a> derecha, as\u00ed como en el exterior de la cadera derecha. Hicimos la resonancia magn\u00e9tica de cadera y rodilla, que mostr\u00f3 desgarro de ra\u00edz medial de la rodilla derecha y bursitis trocant\u00e9rica <a href=\"https:\/\/www.cortho.org\/es\/bursitis-de-cadera-2\/\">de la cadera derecha<\/a>. <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"600\" height=\"591\" data-src=\"\/wp-content\/uploads\/2023\/06\/MRI-Right-hip-non-contrast.png\" alt=\"Resonancia magn\u00e9tica Sin contraste en la cadera derecha\" class=\"wp-image-31032 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/591;\" \/><\/figure>\n<\/div>\n<p class=\"has-text-align-center\"><strong>Resonancia magn\u00e9tica Sin contraste en la cadera derecha<\/strong><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"600\" height=\"591\" data-src=\"\/wp-content\/uploads\/2023\/06\/MRI-Right-hip-non-contrast.png\" alt=\"Resonancia magn\u00e9tica Sin contraste en la cadera derecha\" class=\"wp-image-31032 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/591;\" \/><\/figure>\n<\/div>\n<p class=\"has-text-align-center\"><strong>Resonancia magn\u00e9tica de rodilla derecha sin contraste<\/strong><\/p>\n\n<p>Hablamos sobre las opciones de tratamiento y el paciente opt\u00f3 por el manejo quir\u00fargico. Hablamos sobre riesgos y beneficios, incluyendo infecciones, hemorragias, lesiones en varios nervios y vasos, cirug\u00edas repetidas, necesidad de inyecciones, rehabilitaci\u00f3n, desarrollo de <a href=\"https:\/\/www.cortho.org\/es\/medicina-deportiva\/artritis\/\">artritis<\/a> y necesidad de reemplazo de rodilla en el futuro, entre otros. Tambi\u00e9n hablamos de la inyecci\u00f3n de la cadera derecha. El paciente estuvo de acuerdo y firm\u00f3 un consentimiento informado.   <\/p>\n\n<p>El paciente fue trasladado al quir\u00f3fano, donde se le indujo anestesia general. El paciente fue colocado sobre una mesa de operaciones bien acolchada. Se planific\u00f3 la inyecci\u00f3n de cortisona en la cadera derecha en el lugar, que antes de la anestesia fue se\u00f1alado como el lugar m\u00e1s doloroso.  <\/p>\n\n<p>Despu\u00e9s, se inyectaron 6 mL de Marca\u00edna al 0,5% mezclados con 40 mg de Depo-Medrol en la zona de forma est\u00e9ril. Se le aplic\u00f3 una tirita. Se aplic\u00f3 un torniquete sobre la parte baja del muslo.  <\/p>\n\n<p>La rodilla derecha estaba preparada y colgada as\u00e9pticamente como es habitual. La rodilla derecha estaba sujeta con una pinza en C. Me administraron antibi\u00f3ticos preoperatorios. El torniquete fue elevado tras la aplicaci\u00f3n de Esmarch.   <\/p>\n\n<p>Se cre\u00f3 un portal anterior para un portal de entrada artrosc\u00f3pico lateral y se insert\u00f3 artroscopia. El compartimento patelofemoral mostr\u00f3 cambios osteoartr\u00edticos de grado 1 a grado 2. Hab\u00eda restos en la canaleta medial.  <\/p>\n\n<p>El examen del compartimento tibiofemoral medial mostr\u00f3 una ruptura de la ra\u00edz del menisco medial. Se realiz\u00f3 un portal de entrada medial con el uso de una aguja espinal. Se confirm\u00f3 el desbridamiento de la ra\u00edz menisco y se planific\u00f3 la inserci\u00f3n lateral de la ra\u00edz del menisco.  <\/p>\n\n<p>Hubo cambios osteoartr\u00edticos de grado 1 a grado 2 en el c\u00f3ndilo femoral medial para los que se realiz\u00f3 condroplastia. El examen de la muesca intercondilar mostr\u00f3 LCA intacto. El examen del compartimento tibiofemoral lateral mostr\u00f3 menisco y cart\u00edlago intactos.  <\/p>\n\n<p>El examen del compartimento patelofemoral mostr\u00f3 cambios osteoartr\u00edticos de grado 1 a grado 2, que se obtuvieron con afeitadora. Se planific\u00f3 la reparaci\u00f3n de la ra\u00edz del menisco medial. <\/p>\n\n<p>Se insert\u00f3 una plantilla de reparaci\u00f3n de la ra\u00edz del menisco a trav\u00e9s del portal medial y se coloc\u00f3 a 7,5 mm anterior a la marca posterior. El cortador de flip se insertaba a trav\u00e9s de una incisi\u00f3n separada sobre la tibia medial, guiada por la plantilla. Una vez fuera, se volte\u00f3 y se hizo un t\u00fanel de unos 5 mm.  <\/p>\n\n<p>Curette tambi\u00e9n se utiliz\u00f3 para decorticar el hueso dentro de la rodilla. Se us\u00f3 Scorpion para pasar dos FiberTak por la ra\u00edz, uno profundo y otro superficial. Las suturas se pasaban por el t\u00fanel inter\u00f3seo mediante el uso del pasador de suturas.  <\/p>\n\n<p>Una vez all\u00ed, la ra\u00edz estaba muy bien inducida. Se colocaron suturas en la tibia con el uso de un SwiveLock de 4,75 mm y se logr\u00f3 una buena tensi\u00f3n, que se revis\u00f3 durante la operaci\u00f3n, y se tomaron y guardaron las fotos. <\/p>\n\n<p>La condroplastia por microfractura se realiz\u00f3 usando una p\u00faa de condroplastia de Arthrex con el mango de la afeitadora y se hicieron 4 agujeros. El agua se cort\u00f3 para asegurar que hubiera buen flujo de sangre por esos agujeros. <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"331\" height=\"186\" data-src=\"\/wp-content\/uploads\/2023\/06\/Intraoperative-Arthroscopy-Images-20.png\" alt=\"Im\u00e1genes de artroscopia intraoperatoria\" class=\"wp-image-31030 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 331px; --smush-placeholder-aspect-ratio: 331\/186;\" \/><\/figure>\n<\/div>\n<p class=\"has-text-align-center\"><strong>Im\u00e1genes de artroscopia intraoperatoria<\/strong><\/p>\n\n<p>Se tomaron y guardaron las fotos finales. La rodilla fue completamente irrigada y drenada. El cierre se hizo con el uso de nylon 3-0. El vendaje se realiz\u00f3 con Xeroform, 4 x 4, ABD, Webril y Ace wrap.   <\/p>\n\n<p>Se aplic\u00f3 un inmovilizador de rodilla, que se bloque\u00f3 en extensi\u00f3n con el bloqueo a 90 grados de flexi\u00f3n. El paciente fue extubado y trasladado a Recuperaci\u00f3n en estado estable. <\/p>\n\n<p>El paciente fue atendido para <a href=\"\/faq\/knee\/post-operative-knee-arthroscopy\/\">un chequeo postoperatorio<\/a>. Hemos decidido realizar fisioterapia formal as\u00ed como un programa de ejercicios en casa para la rehabilitaci\u00f3n de la rodilla. Los pacientes segu\u00edan regularmente una visita a la consulta cada 3-4 semanas.  <\/p>\n\n<p>El paciente se recuper\u00f3 bien tras la cirug\u00eda y continu\u00f3 la fisioterapia. El paciente se registr\u00f3 para una visita de seguimiento despu\u00e9s de un mes y not\u00f3 una mejora significativa en la rodilla. <\/p>\n\n<p><em>Aviso legal \u2013 El nombre, edad, sexo, fechas y eventos del paciente han sido modificados o modificados para proteger su privacidad<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una ra\u00edz de menisco que ha sido arrancada puede repararse quir\u00fargicamente. La reparaci\u00f3n meniscal puede realizarse de forma m\u00ednimamente invasiva usando un artroscopio que se introduce en la rodilla a trav\u00e9s de una peque\u00f1a incisi\u00f3n en forma de cerradura para localizar y reparar el menisco lesionado, o puede hacerse abiertamente bajo visi\u00f3n directa. El dolor [&hellip;]<\/p>\n","protected":false},"featured_media":69513,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Estudio de caso: Artroscopia de rodilla y reparaci\u00f3n de la ra\u00edz del menisco | NY","_seopress_titles_desc":"Otro estudio de caso trata sobre la artroscopia de rodilla derecha: reparaci\u00f3n de la ra\u00edz del menisco medial y condroplastia en un paciente de 59 a\u00f1os de Complete Orthopedics.","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"case-study-categories":[176],"case-study-tags":[],"class_list":["post-69511","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case-study-categories-estudios-de-casos-de-medicina-deportiva"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-studies\/69511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/media\/69513"}],"wp:attachment":[{"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/media?parent=69511"}],"wp:term":[{"taxonomy":"case-study-categories","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-study-categories?post=69511"},{"taxonomy":"case-study-tags","embeddable":true,"href":"https:\/\/www.cortho.org\/es\/wp-json\/wp\/v2\/case-study-tags?post=69511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}